{"id":51366,"date":"2026-05-13T13:00:58","date_gmt":"2026-05-13T11:00:58","guid":{"rendered":"https:\/\/rawcyclingmag.com\/?p=51366"},"modified":"2026-05-13T13:00:58","modified_gmt":"2026-05-13T11:00:58","slug":"bmc-kaius-01-the-traka","status":"publish","type":"post","link":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/","title":{"rendered":"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa"},"content":{"rendered":"\n<p class=\"wp-block-wd-paragraph wd-07734a65\">Para las marcas presentes en el mundo del gravel, quiz\u00e1s no haya un lugar de pruebas m\u00e1s importante que <a href=\"https:\/\/rawcyclingmag.com\/es\/the-traka-week-2026\/\" type=\"post\" id=\"51272\" target=\"_blank\" rel=\"noreferrer noopener\">The Traka<\/a>. Lo que comenz\u00f3 como una aventura local de gravel en los alrededores de Girona se ha convertido en un referente mundial de la disciplina, atrayendo a profesionales del WorldTour, ciclistas independientes, medios de comunicaci\u00f3n y pr\u00e1cticamente todas las grandes marcas de ciclismo. Los lanzamientos de productos que antes se realizaban en centros de convenciones y ferias comerciales, ahora tienen lugar en caminos polvorientos, bajo el sol del Mediterr\u00e1neo, rodeados de miles de ciclistas que pondr\u00e1n a prueba esos productos de inmediato.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-1e730736\">Este contexto es crucial al hablar de <a href=\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-en-busca-del-maximo-rendimiento\/\" type=\"post\" id=\"51199\" target=\"_blank\" rel=\"noreferrer noopener\">la nueva BMC Kaius 01<\/a>. BMC no se limit\u00f3 a presentar una nueva bicicleta de gravel; la lanz\u00f3 directamente al caos, la velocidad y la imprevisibilidad de una de las carreras de gravel m\u00e1s duras y competitivas del calendario. Presentar un producto esa semana fue arriesgado, pero aun as\u00ed destac\u00f3 por encima del resto.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-5cd2f1ec\">Tras una primera prueba en Cerde\u00f1a, tuvimos la oportunidad de competir con la Kaius en la prueba de 200 kil\u00f3metros que se celebraba cerca de casa, y nos pareci\u00f3 la forma m\u00e1s pura de comprender para qu\u00e9 estaba realmente dise\u00f1ada esta bicicleta.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1.jpg\"><img decoding=\"async\" width=\"2000\" height=\"1333\" data-id=\"51345\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1.jpg\" alt=\"\" class=\"wp-image-51345\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6265-1-150x100.jpg 150w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1.jpg\"><img decoding=\"async\" width=\"1333\" height=\"2000\" data-id=\"51346\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1.jpg\" alt=\"\" class=\"wp-image-51346\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1.jpg 1333w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6389-1-150x225.jpg 150w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-primeras-impresiones-en-visperas-de-la-carrera\">Primeras impresiones en v\u00edsperas de la carrera<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-3550d3e5\">Recibimos la bicicleta solo un par de d\u00edas antes de la carrera. La elecci\u00f3n de los neum\u00e1ticos se convirti\u00f3 inmediatamente en el tema principal de debate. Pod\u00edamos elegir entre los Continental Dubnital de 50 mm de ancho y los Continental Terra Competition Race Rapid, mucho m\u00e1s rodadores. Finalmente nos decidimos por los Dubnital, m\u00e1s agresivos. \u00bfEra un taqueado excesivo? Quiz\u00e1s, pero como ya conoc\u00edamos la mayor parte de la ruta, preferimos priorizar el confort antes que una m\u00ednima mejora en la resistencia a la rodadura.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-c3e5c804\">El plato de 42 dientes, combinado con el pi\u00f1\u00f3n de 46 dientes del sistema SRAM Red XPLR AXS, fue de nuestro agrado. Sobre el papel, parec\u00eda la configuraci\u00f3n ideal para las empinadas subidas caracter\u00edsticas de The Traka, donde mantener la cadencia suele ser m\u00e1s importante que la velocidad m\u00e1xima. Las ruedas CG 39 SL Carbon, que la marca no promociona en exceso pese a sus interesantes caracter\u00edsticas, eran las que \u00edbamos a usar en la carrera.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-98295a5d\">El d\u00eda anterior a la salida, hicimos una breve y controlada prueba. El objetivo no era poner a prueba nuestra condici\u00f3n f\u00edsica, sino familiarizarnos con la bicicleta: posici\u00f3n, manejo, respuesta y presi\u00f3n de los neum\u00e1ticos. Aun as\u00ed, la curiosidad pronto nos venci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-5236af11\">Tras rodar con facilidad en terreno llano, nos dirigimos hacia un descenso que conoc\u00edamos casi a la perfecci\u00f3n. Un tramo corto pero t\u00e9cnico, lleno de cambios de trazada, curvas cerradas, piedras sueltas y zonas de frenado complicadas. Subimos hasta la cima a ritmo de recuperaci\u00f3n y luego dejamos que la bicicleta rodara en el descenso. Rebajamos en treinta segundos de nuestra marca personal anterior de cuatro minutos.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-abad7357\">Ese resultado no puede atribuirse a un solo componente. No fue solo el cuadro, ni solo los neum\u00e1ticos m\u00e1s anchos. Fue la sensaci\u00f3n de que todo funcionaba en conjunto: estabilidad sin arrastre, velocidad controlada.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455.jpg\"><img decoding=\"async\" width=\"720\" height=\"1080\" data-id=\"51335\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-720x1080.jpg\" alt=\"\" class=\"wp-image-51335\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455-150x225.jpg 150w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5455.jpg 1333w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514.jpg\"><img decoding=\"async\" width=\"720\" height=\"1080\" data-id=\"51339\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-720x1080.jpg\" alt=\"\" class=\"wp-image-51339\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514-150x225.jpg 150w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5514.jpg 1333w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490.jpg\"><img decoding=\"async\" width=\"720\" height=\"1080\" data-id=\"51337\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-720x1080.jpg\" alt=\"\" class=\"wp-image-51337\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490-150x225.jpg 150w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5490.jpg 1333w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-de71dae8\">Regresamos a casa llenos de confianza y con esa peligrosa sensaci\u00f3n que todo ciclista conoce: las ganas de que la carrera empiece ya. Incluso detalles como el adaptador para el dorsal que nos proporcion\u00f3 BMC, perfectamente integrado en la tija de sill\u00edn SP AS 10, reforzaron la impresi\u00f3n de que cada elemento de la Kaius hab\u00eda sido dise\u00f1ado pensando en la competici\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-terreno-de-pruebas-perfecto\">El terreno de pruebas perfecto<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-191ad1f5\">El recorrido de la Traka 200 tiene todo lo que una carrera de gravel puede exigirle a una bicicleta: caminos de tierra r\u00e1pidos, tramos accidentados, subidas exigentes, largas rectas, descensos t\u00e9cnicos y una fatiga acumulada interminable. Era el entorno ideal para evaluar correctamente la Kaius. Como hab\u00edamos recorrido pr\u00e1cticamente toda la ruta por tramos durante las semanas anteriores, tambi\u00e9n cont\u00e1bamos con puntos de comparaci\u00f3n fiables.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556.jpg\"><img decoding=\"async\" width=\"1333\" height=\"2000\" data-id=\"51340\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556.jpg\" alt=\"\" class=\"wp-image-51340\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556.jpg 1333w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5556-150x225.jpg 150w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593.jpg\"><img decoding=\"async\" width=\"1333\" height=\"2000\" data-id=\"51341\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593.jpg\" alt=\"\" class=\"wp-image-51341\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593.jpg 1333w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5593-150x225.jpg 150w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1.jpg\"><img decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-1620x1080.jpg\" alt=\"\" class=\"wp-image-51342\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1-150x100.jpg 150w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF5955-1.jpg 2000w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-d1751c25\">En lugar de enfocarnos en los profesionales del grupo de cabeza, nos centramos en analizar nuestro rendimiento relativo. Fue en la segunda subida de gravel del d\u00eda donde nos encontramos solos y pudimos centrarnos en las caracter\u00edsticas de la Kaius; r\u00e1pidamente nos proporcion\u00f3 una referencia interesante.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-22dc361d\">Hab\u00edamos subido esa cuesta varias veces a alta intensidad en las semanas previas al evento, y a pesar de no gozar de la ventaja de seguir la rueda del de delante, volvimos a mejorar nuestro mejor tiempo con una potencia pr\u00e1cticamente id\u00e9ntica. Ese tipo de mejora es dif\u00edcil de ignorar. Ya fuera por un menor peso del sistema, una mayor eficiencia de rodadura, la geometr\u00eda o simplemente una mayor confianza en terreno suelto, el resultado fue evidente.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-8c0fe09e\">Los descensos, que iban desde caminos lisos hasta tramos t\u00e9cnicos, se sintieron duros a pesar del ancho de nuestros neum\u00e1ticos y de la baja presi\u00f3n. No esper\u00e1bamos un camino de rosas en el descenso, pero fue un recordatorio de que las bicicletas de competici\u00f3n, con una disposici\u00f3n de carbono m\u00e1s orientada a la transferencia de potencia que a la resistencia al impacto, sacrifican la sensaci\u00f3n de conducci\u00f3n en determinadas situaciones para optimizar el rendimiento general.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253.jpg\"><img decoding=\"async\" width=\"1620\" height=\"1080\" data-id=\"51343\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-1620x1080.jpg\" alt=\"\" class=\"wp-image-51343\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253-150x100.jpg 150w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6253.jpg 2000w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287.jpg\"><img decoding=\"async\" width=\"2000\" height=\"1333\" data-id=\"51363\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287.jpg\" alt=\"\" class=\"wp-image-51363\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6287-150x100.jpg 150w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-8c5fa5cc\">M\u00e1s adelante en la carrera lleg\u00f3 <em>Els Metges<\/em>, la subida decisiva de la segunda mitad. Para entonces, el cansancio se hab\u00eda instalado por completo en las piernas. Todo y as\u00ed, tras revisar los datos despu\u00e9s de la carrera, nos dimos cuenta de que hab\u00edamos estado sorprendentemente cerca de igualar una marca personal anterior, lograda en un estado mucho m\u00e1s fresco. Ese fue quiz\u00e1s el indicador m\u00e1s convincente de todos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-donde-las-bicicletas-de-competicion-cobran-sentido\">Donde las bicicletas de competici\u00f3n cobran sentido<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-bb355b1d\">Tras <em>Els Metges<\/em>, el recorrido se convierte en una larga prueba de supervivencia. El perfil de elevaci\u00f3n se vuelve m\u00e1s accesible, pero la fatiga acumulada transforma cada tramo llano en una batalla contra los calambres y la falta de concentraci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930.jpg\"><img decoding=\"async\" width=\"1333\" height=\"2000\" data-id=\"51353\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930.jpg\" alt=\"\" class=\"wp-image-51353\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930.jpg 1333w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF7930-150x225.jpg 150w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1.jpg\"><img decoding=\"async\" width=\"1333\" height=\"2000\" data-id=\"51347\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1.jpg\" alt=\"\" class=\"wp-image-51347\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1.jpg 1333w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6398-1-150x225.jpg 150w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1.jpg\"><img decoding=\"async\" width=\"2000\" height=\"1333\" data-id=\"51348\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1.jpg\" alt=\"\" class=\"wp-image-51348\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6433-1-150x100.jpg 150w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612.jpg\"><img decoding=\"async\" width=\"2000\" height=\"1333\" data-id=\"51351\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612.jpg\" alt=\"\" class=\"wp-image-51351\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF6612-150x100.jpg 150w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-9a069257\">En ese punto, ya era imposible evaluar objetivamente la bicicleta, pues f\u00edsicamente apenas pod\u00edamos mantenernos en pie. Sin embargo, la Kaius nos record\u00f3 claramente su potencial cuando los primeros ciclistas de la categor\u00eda Open nos adelantaron a una velocidad asombrosa.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-4752e2bc\">Entre ellos estaba nuestro amigo <a href=\"https:\/\/www.instagram.com\/tristantakephoto\/\" type=\"link\" id=\"https:\/\/www.instagram.com\/tristantakephoto\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tristan Cardew<\/a>, que tambi\u00e9n compet\u00eda con la Kaius. Ver a los ciclistas mantener esas velocidades en terreno accidentado confirm\u00f3 exactamente lo que BMC pretend\u00eda con esta bicicleta: no una bicicleta de aventura adaptada para la competici\u00f3n, sino una m\u00e1quina de carreras pura, construida espec\u00edficamente para el gravel moderno.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-82116d77\">Finalmente, cubiertos de polvo y entre el agotamiento y la satisfacci\u00f3n, cruzamos la meta.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001.jpg\"><img decoding=\"async\" width=\"1333\" height=\"2000\" data-id=\"51356\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001.jpg\" alt=\"\" class=\"wp-image-51356\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001.jpg 1333w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8001-150x225.jpg 150w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100.jpg\"><img decoding=\"async\" width=\"1333\" height=\"2000\" data-id=\"51361\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100.jpg\" alt=\"\" class=\"wp-image-51361\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100.jpg 1333w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100-720x1080.jpg 720w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100-430x645.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100-700x1050.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8100-150x225.jpg 150w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156.jpg\"><img decoding=\"async\" width=\"2000\" height=\"1333\" data-id=\"51357\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156.jpg\" alt=\"\" class=\"wp-image-51357\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8156-150x100.jpg 150w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196.jpg\"><img decoding=\"async\" width=\"2000\" height=\"1333\" data-id=\"51360\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196.jpg\" alt=\"\" class=\"wp-image-51360\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8196-150x100.jpg 150w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-c7aa4dd9\">Nuestras sensaciones sobre nuestro propio rendimiento fueron contradictorias. The Traka rara vez deja a los ciclistas completamente satisfechos. Pero en cuanto a la bicicleta, la conclusi\u00f3n fue inmediata. Devolvimos la Kaius a los representantes de BMC en el lugar casi a rega\u00f1adientes, porque una vez que experimentas la sensaci\u00f3n de exprimir una aut\u00e9ntica bicicleta de gravel de competici\u00f3n a gran velocidad, devolverla resulta sorprendentemente dif\u00edcil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-gravel-ha-cambiado-y-la-kaius-tambien\">El gravel ha cambiado, y la Kaius tambi\u00e9n<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-68041718\">En perspectiva, quiz\u00e1s el cambio m\u00e1s relevante de la nueva Kaius no sea su enfoque aerodin\u00e1mico ni la reducci\u00f3n de peso, sino el mayor paso de rueda.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-d5991cc6\">Las carreras de gravel modernas han evolucionado r\u00e1pidamente. Los neum\u00e1ticos m\u00e1s anchos ya no se reservan para terrenos extremos, sino que se est\u00e1n convirtiendo en un est\u00e1ndar incluso en carreras r\u00e1pidas. Cuando se lanz\u00f3 la anterior Kaius, su paso de rueda de 44 mm se convirti\u00f3 r\u00e1pidamente en una limitaci\u00f3n. Los ciclistas patrocinados por BMC a menudo ten\u00edan que hacer concesiones dependiendo del evento.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-b0e7090a\">Por ejemplo, el a\u00f1o pasado en <a href=\"https:\/\/rawcyclingmag.com\/es\/vida-de-campamento-en-la-primera-edicion-de-la-gravel-burn-es\/\" type=\"post\" id=\"49841\" target=\"_blank\" rel=\"noreferrer noopener\">Gravel Burn<\/a>, vimos c\u00f3mo Simone Pellaud eligi\u00f3 la URS en lugar de la anterior Kaius simplemente para poder usar el ancho de neum\u00e1tico deseado. El nuevo modelo cambia por completo esta situaci\u00f3n. Ahora ofrece a\u00fan mayor espacio para los neum\u00e1ticos que la URS, eliminando lo que se hab\u00eda convertido en la mayor desventaja competitiva de la plataforma.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-30cd24e0\">Durante toda la carrera, la configuraci\u00f3n funcion\u00f3 a la perfecci\u00f3n. Los portabidones Aerocore sujetaron bidones de 750 ml de forma segura incluso en terrenos irregulares, y la bicicleta mantuvo un equilibrio constante entre velocidad y estabilidad, con una sensaci\u00f3n claramente moderna.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-1fdfa0b2\">Aunque no hemos podido probar la Kaius anterior, la evoluci\u00f3n es claramente visible. La geometr\u00eda parece ligeramente m\u00e1s relajada, con una altura de cuadro mayor, un alcance m\u00e1s corto y un pedalier m\u00e1s alto debido al mayor espacio libre para los neum\u00e1ticos. Estos cambios pueden parecer sutiles en una tabla de geometr\u00eda, pero tras 200 kil\u00f3metros de carrera, se vuelven significativos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233.jpg\"><img decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-1620x1080.jpg\" alt=\"\" class=\"wp-image-51359\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-1620x1080.jpg 1620w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-400x267.jpg 400w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-430x287.jpg 430w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-700x467.jpg 700w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233-150x100.jpg 150w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8233.jpg 2000w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-4333933b\">Y quiz\u00e1s esa sea, en definitiva, la mejor descripci\u00f3n tanto de la Kaius como del ciclismo de gravel moderno. Las peque\u00f1as mejoras siguen importando, pero solo si ayudan a los ciclistas a mantener el ritmo en las partes finales de la carrera, cuando la fatiga, el terreno y la toma de decisiones empiezan a ser m\u00e1s importantes que las cifras brutas.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-66ca5161\">The Traka sigue siendo una de las pocas pruebas capaces de determinar si una bicicleta de gravel est\u00e1 realmente preparada para la competici\u00f3n o simplemente se comercializa como tal. Tras 200 kil\u00f3metros polvorientos alrededor de Girona, la nueva Kaius 01 forma claramente parte del primer grupo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primeras impresiones en v\u00edsperas de la carrera El terreno de pruebas perfecto Donde las bicicletas de competici\u00f3n cobran sentido El<\/p>\n","protected":false},"author":11,"featured_media":51362,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4079,4080],"tags":[4544],"class_list":["post-51366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-eventos","tag-the-traka"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa - RAW Cycling Magazine<\/title>\n<meta name=\"description\" content=\"The Traka remains one of the few events capable of exposing whether a gravel bike is genuinely race-ready or simply marketed as such. After 200 dusty kilometers around Girona, the new BMC Kaius 01 felt very much like the former.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa\" \/>\n<meta property=\"og:description\" content=\"The Traka remains one of the few events capable of exposing whether a gravel bike is genuinely race-ready or simply marketed as such. After 200 dusty kilometers around Girona, the new BMC Kaius 01 felt very much like the former.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/\" \/>\n<meta property=\"og:site_name\" content=\"RAW Cycling Magazine\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/rawcyclingmag\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186-1620x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Javi Angulo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:site\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javi Angulo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/\"},\"author\":{\"name\":\"Javi Angulo\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2\"},\"headline\":\"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa\",\"datePublished\":\"2026-05-13T11:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/\"},\"wordCount\":1643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg\",\"keywords\":[\"the traka\"],\"articleSection\":[\"Destacado\",\"Eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/\",\"name\":\"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa - RAW Cycling Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg\",\"datePublished\":\"2026-05-13T11:00:58+00:00\",\"description\":\"The Traka remains one of the few events capable of exposing whether a gravel bike is genuinely race-ready or simply marketed as such. After 200 dusty kilometers around Girona, the new BMC Kaius 01 felt very much like the former.\",\"breadcrumb\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"BMC Kaius finish The Traka\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/rawcyclingmag.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"name\":\"RAW Cycling Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\",\"name\":\"RAW Cycling Magazine\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"width\":300,\"height\":140,\"caption\":\"RAW Cycling Magazine\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/facebook.com\/rawcyclingmag\",\"https:\/\/x.com\/rawcyclingmag\",\"http:\/\/instagram.com\/rawcyclingmag\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2\",\"name\":\"Javi Angulo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g\",\"caption\":\"Javi Angulo\"},\"description\":\"Javi es nuestro corresponsal en B\u00e9lgica, y trata de contrarrestar su obsesiva pasi\u00f3n por el an\u00e1lisis de datos con la relajante acci\u00f3n (o eso es lo que dice) de crear contenido para la revista. Javi is based in Belgium and tries to compensate for his obsessive passion for data analytics with the relaxing action (that's what he says) of creating content for the magazine.\",\"sameAs\":[\"https:\/\/www.instagram.com\/javiangulog\/\"],\"url\":\"https:\/\/rawcyclingmag.com\/es\/author\/javi\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa - RAW Cycling Magazine","description":"The Traka remains one of the few events capable of exposing whether a gravel bike is genuinely race-ready or simply marketed as such. After 200 dusty kilometers around Girona, the new BMC Kaius 01 felt very much like the former.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/","og_locale":"es_ES","og_type":"article","og_title":"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa","og_description":"The Traka remains one of the few events capable of exposing whether a gravel bike is genuinely race-ready or simply marketed as such. After 200 dusty kilometers around Girona, the new BMC Kaius 01 felt very much like the former.","og_url":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/","og_site_name":"RAW Cycling Magazine","article_publisher":"http:\/\/facebook.com\/rawcyclingmag","article_published_time":"2026-05-13T11:00:58+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186-1620x1080.jpg","type":"image\/jpeg"}],"author":"Javi Angulo","twitter_card":"summary_large_image","twitter_creator":"@rawcyclingmag","twitter_site":"@rawcyclingmag","twitter_misc":{"Escrito por":"Javi Angulo","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#article","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/"},"author":{"name":"Javi Angulo","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2"},"headline":"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa","datePublished":"2026-05-13T11:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/"},"wordCount":1643,"commentCount":0,"publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg","keywords":["the traka"],"articleSection":["Destacado","Eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/","url":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/","name":"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa - RAW Cycling Magazine","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg","datePublished":"2026-05-13T11:00:58+00:00","description":"The Traka remains one of the few events capable of exposing whether a gravel bike is genuinely race-ready or simply marketed as such. After 200 dusty kilometers around Girona, the new BMC Kaius 01 felt very much like the former.","breadcrumb":{"@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#primaryimage","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2026\/05\/DSF8186.jpg","width":2000,"height":1333,"caption":"BMC Kaius finish The Traka"},{"@type":"BreadcrumbList","@id":"https:\/\/rawcyclingmag.com\/es\/bmc-kaius-01-the-traka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rawcyclingmag.com\/es\/"},{"@type":"ListItem","position":2,"name":"Probando la nueva BMC Kaius 01 en la carrera de gravel m\u00e1s importante de Europa"}]},{"@type":"WebSite","@id":"https:\/\/rawcyclingmag.com\/es\/#website","url":"https:\/\/rawcyclingmag.com\/es\/","name":"RAW Cycling Magazine","description":"","publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rawcyclingmag.com\/es\/#organization","name":"RAW Cycling Magazine","url":"https:\/\/rawcyclingmag.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","width":300,"height":140,"caption":"RAW Cycling Magazine"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/rawcyclingmag","https:\/\/x.com\/rawcyclingmag","http:\/\/instagram.com\/rawcyclingmag"]},{"@type":"Person","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2","name":"Javi Angulo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g","caption":"Javi Angulo"},"description":"Javi es nuestro corresponsal en B\u00e9lgica, y trata de contrarrestar su obsesiva pasi\u00f3n por el an\u00e1lisis de datos con la relajante acci\u00f3n (o eso es lo que dice) de crear contenido para la revista. Javi is based in Belgium and tries to compensate for his obsessive passion for data analytics with the relaxing action (that's what he says) of creating content for the magazine.","sameAs":["https:\/\/www.instagram.com\/javiangulog\/"],"url":"https:\/\/rawcyclingmag.com\/es\/author\/javi\/"}]}},"_links":{"self":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/51366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/comments?post=51366"}],"version-history":[{"count":3,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/51366\/revisions"}],"predecessor-version":[{"id":51370,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/51366\/revisions\/51370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media\/51362"}],"wp:attachment":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media?parent=51366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/categories?post=51366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/tags?post=51366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}