{"id":37037,"date":"2022-07-05T15:57:34","date_gmt":"2022-07-05T13:57:34","guid":{"rendered":"https:\/\/raw.ecoolabs.com\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/"},"modified":"2025-04-27T12:15:52","modified_gmt":"2025-04-27T10:15:52","slug":"transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes","status":"publish","type":"post","link":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/","title":{"rendered":"TransPyrenees 2022: La meteo, el mayor rival para los participantes"},"content":{"rendered":"<p>Otro a\u00f1o, <a href=\"https:\/\/rawcyclingmag.com\/transpyrenees-2020-film\/\" target=\"_blank\" rel=\"noopener\">otra edici\u00f3n exitosa<\/a> de la siempre desafiante carrera de ultraciclismo de carretera a trav\u00e9s de los Pirineos. Con salida en el pueblo mediterr\u00e1neo de Llan\u00e7\u00e0, situado en la comarca catalana del Alt Empord\u00e0, y meta en la ciudad vasca de San Sebasti\u00e1n, al sur del Cant\u00e1brico, la <a href=\"https:\/\/www.transiberica.club\/transpyrenees\/\" target=\"_blank\" rel=\"noopener\">TransPyrenees<\/a> ha contado este a\u00f1o con 115 corredores inscritos en la categor\u00eda individual y 40 en la de parejas.<\/p>\n<p><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-16998\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1.jpg\" alt=\"\" width=\"1998\" height=\"1334\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1.jpg 1998w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1-1024x684.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1-1536x1026.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_1-272x182.jpg 272w\" sizes=\"(max-width: 1998px) 100vw, 1998px\" \/><\/a><\/p>\n<p>El objetivo de la carrera es claro, pero para hacerla m\u00e1s interesante, a\u00f1o tras a\u00f1o, la organizaci\u00f3n de la carrera cambia el recorrido trayendo nuevas sorpresas. A diferencia del a\u00f1o pasado en la que el recorrido transcurri\u00f3 mayormente por la vertiente espa\u00f1ola, esta vez la carrera volv\u00eda a los or\u00edgenes, recuperando su ruta a trav\u00e9s del Pirineo Franc\u00e9s. Los ciclistas tuvieron que subir 33 puertos, cubriendo un total de 1.080 km con +25.000 m de desnivel positivo. La ruta inclu\u00eda muchos puertos ic\u00f3nicos del Tour de Francia, el puerto de monta\u00f1a m\u00e1s alto de los Pirineos (Envalira a 2.409 m) y, una novedad para este a\u00f1o, el ascenso a Lac de Cap de Long, un puerto de sentido \u00fanico con cerca de 23 km de longitud y un tramo final duro a la vez que bonito.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-37037 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-1-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-3-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_2-2-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<h3>La carrera<\/h3>\n<p>El tiempo en la monta\u00f1a puede ser impredecible y, tras una ola de calor en el sur de Europa una semana antes del inicio de la carrera, los corredores de la <a href=\"https:\/\/www.instagram.com\/transiberica_club\/\" target=\"_blank\" rel=\"noopener\">TransPyrenees<\/a> no pod\u00edan imaginar lo que les estaba esperando. Con un inicio relativamente tranquilo a las 20h del s\u00e1bado 25 de junio, nada m\u00e1s caer la noche las temperaturas bajaron hasta los 5 \u00baC y todo el mundo se vio obligado a ponerse toda la ropa que llevaban en las mochilas, desde perneras, a guantes y chaquetas de lluvia con capucha.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-37037 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-3-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-2-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_1_1-1-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Todas esas prendas extras se convertir\u00edan en imprescindibles para el resto de la carrera, ya que pronto se instal\u00f3 el mal tiempo, con lluvia, niebla y fr\u00edo. Subir un puerto bajo la lluvia puede resultar algo casi placentero, sin embargo, descender por puertos de tal envergadura como los de los Pirineos puede convertirse en una pesadilla, ya que el fr\u00edo y los escalofr\u00edos te pueden invadir y hay que ser extremadamente cauteloso en cada curva.<\/p>\n<p><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-16987\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large.jpg\" alt=\"\" width=\"2000\" height=\"1334\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3_large-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-37037 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-1-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-2-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_3-3-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>A pesar de eso, todos y cada uno de los ciclistas decidieron superar sus l\u00edmites, como es el objetivo de cualquier carrera de ultradistancia, y se enfrentaron a las terribles condiciones clim\u00e1ticas con todos sus esfuerzos. Esto implica fuerza f\u00edsica pero especialmente mental a lo largo de la carrera para conquistar los m\u00edticos puertos de La Bonaigua, Portilhon, Peyresourde, Aspin, Tourmalet, o Aubisque, entre otros, y a la vez cruzar la frontera entre Espa\u00f1a, Andorra y Francia varias veces.<\/p>\n<p><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-16977\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2.jpg\" alt=\"\" width=\"2000\" height=\"1334\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover_2-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-4 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-4 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-4' class='gallery galleryid-37037 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-2-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-3-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1.jpg'><img decoding=\"async\" width=\"1998\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1.jpg 1998w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1-1024x684.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1-1536x1026.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_4-1-272x182.jpg 272w\" sizes=\"(max-width: 1998px) 100vw, 1998px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>El primero en llegar a meta fue el alem\u00e1n, Adam Bialek, con un incre\u00edble tiempo de 54h 40min y sin apenas equipaje encima. A pesar de ser seguido de cerca en el inicio de la carrera por el vasco Patxi Plazaola, este se retir\u00f3 por las condiciones meteorol\u00f3gicas. Sin embargo, no fue el \u00fanico que se vio forzado a hacerlo, con m\u00e1s de 20 DNFs (do not finish). El segundo en llegar fue el belga Christophe Dijkmans (67h 16min) seguido del brit\u00e1nico Adam Palin (74h 11min). Echando un vistazo a los tiempos, est\u00e1 claro que el clima hizo las cosas bastante dif\u00edciles para todos, lo que result\u00f3 en grandes diferencias de tiempo entre todos los contendientes.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-5 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-5 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-5' class='gallery galleryid-37037 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-1-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/large_2_Biteofme-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-2-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_5_2x2-4-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Con una actuaci\u00f3n espectacular, la ciclista suiza Silvia Perrenoud lleg\u00f3 s\u00e9ptima en la general y cruz\u00f3 la l\u00ednea de meta como primera mujer con un tiempo de 81h 40min. Medio d\u00eda despu\u00e9s llegaba la primera pareja, formada por el d\u00fao vasco formado por Ra\u00fal Peralta y Jokin Etxebarria que par\u00f3 el cron\u00f3metro con 93h 14min.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-6 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-6 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-6' class='gallery galleryid-37037 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-2-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3.jpg'><img decoding=\"async\" width=\"1999\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3.jpg 1999w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3-768x513.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/day_6-3-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/Raul_large-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Otro a\u00f1o, otra edici\u00f3n exitosa de la siempre desafiante carrera de ultraciclismo de carretera a trav\u00e9s de los Pirineos. Con<\/p>\n","protected":false},"author":12,"featured_media":32132,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4079,4080],"tags":[4307,4073,4121,4072,4082,4266],"class_list":["post-37037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-eventos","tag-ultradistance-es","tag-ultracycling-es","tag-road-cycling-es","tag-transiberica-es","tag-bikepacking-es","tag-transpyrenees-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TransPyrenees 2022: La meteo, el mayor rival para los participantes - RAW Cycling Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TransPyrenees 2022: La meteo, el mayor rival para los participantes\" \/>\n<meta property=\"og:description\" content=\"Otro a\u00f1o, otra edici\u00f3n exitosa de la siempre desafiante carrera de ultraciclismo de carretera a trav\u00e9s de los Pirineos. Con\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/\" \/>\n<meta property=\"og:site_name\" content=\"RAW Cycling Magazine\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/rawcyclingmag\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-05T13:57:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-27T10:15:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1999\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pol Sope\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:site\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pol Sope\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/\"},\"author\":{\"name\":\"Pol Sope\u00f1a\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483\"},\"headline\":\"TransPyrenees 2022: La meteo, el mayor rival para los participantes\",\"datePublished\":\"2022-07-05T13:57:34+00:00\",\"dateModified\":\"2025-04-27T10:15:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/\"},\"wordCount\":709,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg\",\"keywords\":[\"ultradistance\",\"ultracycling\",\"road cycling\",\"TransIb\u00e9rica\",\"bikepacking\",\"TransPyrenees\"],\"articleSection\":[\"Destacado\",\"Eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/\",\"name\":\"TransPyrenees 2022: La meteo, el mayor rival para los participantes - RAW Cycling Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg\",\"datePublished\":\"2022-07-05T13:57:34+00:00\",\"dateModified\":\"2025-04-27T10:15:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg\",\"width\":1999,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/rawcyclingmag.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TransPyrenees 2022: La meteo, el mayor rival para los participantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"name\":\"RAW Cycling Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\",\"name\":\"RAW Cycling Magazine\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"width\":300,\"height\":140,\"caption\":\"RAW Cycling Magazine\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/facebook.com\/rawcyclingmag\",\"https:\/\/x.com\/rawcyclingmag\",\"http:\/\/instagram.com\/rawcyclingmag\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483\",\"name\":\"Pol Sope\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g\",\"caption\":\"Pol Sope\u00f1a\"},\"description\":\"Apasionado de la bici y de la competici\u00f3n, Pol, siempre est\u00e1 preparado para una nueva aventura. Le encanta la sensaci\u00f3n de ponerse un dorsal y es un aut\u00e9ntico adicto al ciclocros. Passionate about bikes and racing, Pol is always ready for a new adventure. He loves the feeling of pinning a number and he is truly addicted to cyclocross.\",\"sameAs\":[\"https:\/\/www.instagram.com\/polsope\/\"],\"url\":\"https:\/\/rawcyclingmag.com\/es\/author\/pol\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TransPyrenees 2022: La meteo, el mayor rival para los participantes - RAW Cycling Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/","og_locale":"es_ES","og_type":"article","og_title":"TransPyrenees 2022: La meteo, el mayor rival para los participantes","og_description":"Otro a\u00f1o, otra edici\u00f3n exitosa de la siempre desafiante carrera de ultraciclismo de carretera a trav\u00e9s de los Pirineos. Con","og_url":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/","og_site_name":"RAW Cycling Magazine","article_publisher":"http:\/\/facebook.com\/rawcyclingmag","article_published_time":"2022-07-05T13:57:34+00:00","article_modified_time":"2025-04-27T10:15:52+00:00","og_image":[{"width":1999,"height":1334,"url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg","type":"image\/jpeg"}],"author":"Pol Sope\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@rawcyclingmag","twitter_site":"@rawcyclingmag","twitter_misc":{"Escrito por":"Pol Sope\u00f1a","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#article","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/"},"author":{"name":"Pol Sope\u00f1a","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483"},"headline":"TransPyrenees 2022: La meteo, el mayor rival para los participantes","datePublished":"2022-07-05T13:57:34+00:00","dateModified":"2025-04-27T10:15:52+00:00","mainEntityOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/"},"wordCount":709,"commentCount":0,"publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg","keywords":["ultradistance","ultracycling","road cycling","TransIb\u00e9rica","bikepacking","TransPyrenees"],"articleSection":["Destacado","Eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/","url":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/","name":"TransPyrenees 2022: La meteo, el mayor rival para los participantes - RAW Cycling Magazine","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg","datePublished":"2022-07-05T13:57:34+00:00","dateModified":"2025-04-27T10:15:52+00:00","breadcrumb":{"@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#primaryimage","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2022\/07\/cover.jpg","width":1999,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/rawcyclingmag.com\/es\/transpyrenees-2022-la-meteo-el-mayor-rival-para-los-participantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rawcyclingmag.com\/es\/"},{"@type":"ListItem","position":2,"name":"TransPyrenees 2022: La meteo, el mayor rival para los participantes"}]},{"@type":"WebSite","@id":"https:\/\/rawcyclingmag.com\/es\/#website","url":"https:\/\/rawcyclingmag.com\/es\/","name":"RAW Cycling Magazine","description":"","publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rawcyclingmag.com\/es\/#organization","name":"RAW Cycling Magazine","url":"https:\/\/rawcyclingmag.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","width":300,"height":140,"caption":"RAW Cycling Magazine"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/rawcyclingmag","https:\/\/x.com\/rawcyclingmag","http:\/\/instagram.com\/rawcyclingmag"]},{"@type":"Person","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483","name":"Pol Sope\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g","caption":"Pol Sope\u00f1a"},"description":"Apasionado de la bici y de la competici\u00f3n, Pol, siempre est\u00e1 preparado para una nueva aventura. Le encanta la sensaci\u00f3n de ponerse un dorsal y es un aut\u00e9ntico adicto al ciclocros. Passionate about bikes and racing, Pol is always ready for a new adventure. He loves the feeling of pinning a number and he is truly addicted to cyclocross.","sameAs":["https:\/\/www.instagram.com\/polsope\/"],"url":"https:\/\/rawcyclingmag.com\/es\/author\/pol\/"}]}},"_links":{"self":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/37037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/comments?post=37037"}],"version-history":[{"count":0,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/37037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media\/32132"}],"wp:attachment":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media?parent=37037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/categories?post=37037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/tags?post=37037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}