{"id":36855,"date":"2021-04-26T22:30:53","date_gmt":"2021-04-26T20:30:53","guid":{"rendered":"https:\/\/raw.ecoolabs.com\/marley-blonsky-all-bodies-on-bikes\/"},"modified":"2021-04-26T22:30:53","modified_gmt":"2021-04-26T20:30:53","slug":"marley-blonsky-all-bodies-on-bikes","status":"publish","type":"post","link":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/","title":{"rendered":"Marley Blonsky: All bodies on bikes"},"content":{"rendered":"<p>Hace unos d\u00edas, Shimano lanz\u00f3 el video <a href=\"https:\/\/www.youtube.com\/watch?v=JytAXpxmmQY&amp;ab_channel=%23RideShimano\" target=\"_blank\" rel=\"noopener\"><em>All bodies on bikes<\/em><\/a>, en la que <a href=\"https:\/\/linktr.ee\/marleyblonsky\" target=\"_blank\" rel=\"noopener\">Marley Blonsky<\/a> y <a href=\"https:\/\/linktr.ee\/KornhauserSauce\" target=\"_blank\" rel=\"noopener\">Kailey Kornhauser<\/a> realizan un viaje en bicicleta por Oregon (EEUU). Por norma general, cuando pensamos en ciclistas, lo que nos viene a la cabeza es el Tour de Francia y un grupo de chicos delgados pedaleando entre la muchedumbre. Sin embargo, en esta pel\u00edcula podemos ver que el ciclismo es mucho m\u00e1s que eso y que no se limita a un estereotipo de cuerpo.<\/p>\n<p>Tuvimos la suerte de poder hablar con <a href=\"https:\/\/www.instagram.com\/marleyblonsky\/\" target=\"_blank\" rel=\"noopener\">Marley Blonsky<\/a>, quien a lo largo de los a\u00f1os ha ido disfrutando de la bici cada vez m\u00e1s y m\u00e1s, desde algo simple y b\u00e1sico como ir al trabajo, hasta atreverse con el ciclismo de aventura. Charlamos un poco con ella acerca de su modo de percibir el ciclismo, y del rol que ella y <a href=\"https:\/\/www.instagram.com\/kornhausersauce\/\" target=\"_blank\" rel=\"noopener\">Kailey Kornhauser<\/a> ocupan en el proyecto. Intentan dar visibilidad y proveer soluciones para gente gorda a quienes les gusta ir en bicicleta, porque \u201cdeber\u00edas aceptar tu cuerpo y simplemente disfrutar lo que haces\u201d.<\/p>\n<p><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13964\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical.jpg\" alt=\"\" width=\"1333\" height=\"2000\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical.jpg 1280w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical-682x1024.jpg 682w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical-768x1152.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical-1024x1536.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/vertical-600x900.jpg 600w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-36855 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/17-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/16-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/18-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><strong>\u00bfNos podr\u00edas dar una peque\u00f1a descripci\u00f3n tuya para aquellos que no te conocen?<\/strong><\/p>\n<blockquote><p>Me llamo Marley Blonsky, me identifico como una mujer gorda y me gusta ir en bici. He ido en bici b\u00e1sicamente toda mi vida. No pensaba que mi situaci\u00f3n fuese algo sorprendente y de inter\u00e9s para la gente. Lo hac\u00eda porque me divert\u00eda y para desplazarme en mi ciudad. Iba del trabajo a casa y viceversa, y luego empec\u00e9 con bikepacking. A partir de ese momento la gente me empez\u00f3 a escribir y preguntarme c\u00f3mo lo hac\u00eda al ser una persona gorda, qu\u00e9 ropa llevaba, y qu\u00e9 material usaba, etc. Me d\u00ed cuenta que esto era \u00fanico, que ten\u00eda un conocimiento a transmitir, y que pod\u00eda mejorar la vida de mucha gente. As\u00ed que empec\u00e9 a escribir un blog y compartir mis experiencias, no solo sobre las aventuras y el d\u00eda a d\u00eda de commuting, tambi\u00e9n trat\u00e9 de relatar lo que implica ser una persona de mis caracter\u00edsticas e ir en bicicleta.<\/p><\/blockquote>\n<p><strong>Como persona gorda, \u00bfencontraste muchos obst\u00e1culos?<\/strong><\/p>\n<blockquote><p>Un claro ejemplo, es el tema de la ropa. Normalmente me apa\u00f1aba con lo que pod\u00eda encontrar. Era dif\u00edcil conseguir una talla grande, y eso que no soy excesivamente grande. Escrib\u00ed muchos mensajes a grandes empresas para ver si pod\u00edan hacer tallas m\u00e1s grandes. La respuesta habitual era \u201cestamos trabajando en ello, pero no creemos que haya suficiente demanda\u201d. Eso pas\u00f3 en m\u00e1s de 50 ocasiones. Finalmente, hubo una empresa que estuvo dispuesta a enviarme unos cuantos productos para probar. Eso sucedi\u00f3 hace dos a\u00f1os y la primera sensaci\u00f3n que tuve al ponerme un culote, fue incre\u00edble el hecho de poder usar ropa t\u00e9cnica. Me hab\u00eda re\u00eddo varias veces de los \u2018carreteros\u2019 y la gente que lleva lycra simplemente porque me sent\u00eda desplazada. Una vez me pude poner una equipaci\u00f3n entera, lo entend\u00ed, todo cobr\u00f3 sentido. A\u00fan no hay muchos productos disponibles, pero acabo de recibir mi chubasquero espec\u00edfico de <a href=\"https:\/\/www.instagram.com\/pearlizumiofficial\/\" target=\"_blank\" rel=\"noopener\">Pearl Izumi<\/a>, para quienes soy embajadora, y es incre\u00edble.<\/p><\/blockquote>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-36855 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/13-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/14-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/12-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/11-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><strong>\u00bfC\u00f3mo empez\u00f3 el proyecto <a href=\"https:\/\/www.instagram.com\/allbodiesonbikes\/\" target=\"_blank\" rel=\"noopener\"><em>All bodies on bikes<\/em><\/a>?<\/strong><\/p>\n<blockquote><p>Kailey y yo hac\u00edamos talleres y clases para hacer tu club ciclista u organizaci\u00f3n m\u00e1s inclusiva para todo el mundo. Hab\u00edamos participado en un par de conferencias cuando apareci\u00f3 el Covid-19 y empezamos a hacerlo de manera virtual. Kailey hab\u00eda estudiado con el <a href=\"https:\/\/www.instagram.com\/zeppelinzeerip\/\" target=\"_blank\" rel=\"noopener\">director<\/a> de la pel\u00edcula. \u00c9l vi\u00f3 una de sus presentaciones y pens\u00f3 que ser\u00eda una buena historia para contar en una pel\u00edcula. Entonces, decidi\u00f3 ponerse en contacto con <a href=\"https:\/\/www.instagram.com\/rideshimano\/\" target=\"_blank\" rel=\"noopener\">Shimano<\/a> para conseguir financiaci\u00f3n y ellos, sorprendentemente, aceptaron. Nuestro objetivo no era hacer una pel\u00edcula, pero estamos super agradecidas que el mensaje se haya podido transmitir a este nivel y velocidad. Si no hubiese sido as\u00ed, a\u00fan estar\u00edamos dando charlas a grupos de 10 personas.<\/p><\/blockquote>\n<p><strong>\u00bfCu\u00e1l fue el rol de una empresa tan grande como Shimano?<\/strong><\/p>\n<blockquote><p>Han sido maravillosos y nos han apoyado al 100% en muchos aspectos. Nos han tratado como iguales y atletas. Ha sido una gran experiencia y no nos han encasillado. No ha sido aposta, pero ahora tienen dos embajadoras gordas que pueden ser el modelo para otra gente y alcanzar una audiencia m\u00e1s general, al final, una consecuencia del proyecto. Tengo la impresi\u00f3n que sus equipos tambi\u00e9n han aprendido un mont\u00f3n en c\u00f3mo mejorar.<\/p><\/blockquote>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-36855 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/8-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/9-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/10-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><strong>Ahora que el v\u00eddeo ya est\u00e1 disponible, \u00bfhab\u00e9is recibido m\u00e1s atenci\u00f3n?<\/strong><\/p>\n<blockquote><p>Si, definitivamente. Una gran variedad de personas nos han aceptado, incluso aquellos que se centran en competir y estar en forma. Han visto que Kailey y yo nos divertimos, y se identifican con eso. No hemos recibido negatividad, sino lo opuesto. A trav\u00e9s de Shimano, nos hemos puesto en contacto con bicicletas <a href=\"https:\/\/www.instagram.com\/giantbicycles\/\" target=\"_blank\" rel=\"noopener\">Giant<\/a> y un par m\u00e1s de empresas. S\u00e9 que el cambio es lento. Por ejemplo, en ropa, las marcas dise\u00f1an sus modelos dos temporadas por avanzado. Simplemente queremos que las marcas se den cuenta que hay mucha gente gorda que va en bici y que quiere ropa funcional.<\/p><\/blockquote>\n<p><strong>Aparte de cursos y clases, \u00bfcu\u00e1l ser\u00e1 el siguiente paso?<\/strong><\/p>\n<blockquote><p>A medida que la gente se vacune empezaremos a organizar salidas en grupo para principiantes y luego viajes en bicicleta para grupos mixtos tambi\u00e9n. Ser\u00eda genial poder ver m\u00e1s y m\u00e1s gente con cuerpos grandes, y luego grupos mixtos. No hemos acabado de ver qu\u00e9 pinta tendr\u00e1 eso ya que Kailey vive en Oregon y yo en Washington, y es dif\u00edcil de gestionarlo. Sin embargo, seguiremos dando clases y estamos abiertas a colaborar con empresas y otras organizaciones. Tambi\u00e9n estar\u00eda bien poder hacer viajes al estranjero o retiros.<\/p><\/blockquote>\n<p><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13968\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1.jpg\" alt=\"\" width=\"2000\" height=\"1200\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1.jpg 1920w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/5-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-4 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-4 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-4' class='gallery galleryid-36855 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/2-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/15-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/4-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><strong>\u00bfEst\u00e1is planeando hacer del proyecto un movimiento internacional?<\/strong><\/p>\n<blockquote><p>Tenemos una llamada programada con Shimano-Europe, al menos con los equipos de ventas y marketing. Una gran parte del proyecto es formar a los empleados de tienda y representantes comerciales a como tener conversaciones y tratar a todo el mundo por igual. Por ejemplo, c\u00f3mo ser m\u00e1s inclusivo cuando est\u00e1s liderando una salida en grupo. El grupo de FB o la cuenta de IG han ayudado un mont\u00f3n a transmitir el mensaje. Tambi\u00e9n hacemos salidas <a href=\"https:\/\/rawcyclingmag.com\/movistar-eteam-pioneers-among-worldteams\/\" target=\"_blank\" rel=\"noopener\">Zwift<\/a> cada viernes, pero tenemos que a\u00f1adir a todo el mundo de manera individual y no es muy pr\u00e1ctico. Estamos intentando ser un grupo oficial para poder organizar \u2018meet-ups\u2019 y crear una comunidad mundial. Una vez podamos viajar, nos gustar\u00eda poder decir \u2018Hey, Kailey y yo estamos en Par\u00eds, \u00bfquedamos para una salida?\u2019. Con Bikeshare por todo el mundo, esto es m\u00e1s f\u00e1cil. Este es el plan, pero est\u00e1 todo un poco parado ahora mismo.<\/p><\/blockquote>\n<p><strong>Me sorprendi\u00f3 el hecho que no s\u00f3lo sois dos personas gordas sino tambi\u00e9n dos mujeres. Al final del video hay un grupo de personas en bici, casi todas mujeres. \u00bfQu\u00e9 papel juega el g\u00e9nero femenino en el proyecto?<\/strong><\/p>\n<blockquote><p>Bueno, en el video salen los amigos que pude localizar en ese momento. Sin embargo, parece ser que hay una tendencia hacia las mujeres, pero tambi\u00e9n hay muchos movimientos que se identifican de este modo. No se si es porque Kailey y yo somos mujeres y nuestras voces resuenan m\u00e1s en ellas. S\u00e9 que hay hombres gordos que van en bici tambi\u00e9n. Quiz\u00e1s dudan m\u00e1s a la hora de identificarse de este modo. En cualquier caso, hay m\u00e1s mujeres que hombres que est\u00e1n buscando esta comunidad, pero est\u00e1 abierto a todo el mundo.<\/p><\/blockquote>\n<p><a href=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13963\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance.jpg\" alt=\"\" width=\"1999\" height=\"1333\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance.jpg 1920w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/dance-272x182.jpg 272w\" sizes=\"(max-width: 1999px) 100vw, 1999px\" \/><\/a><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-5 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-5 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-5' class='gallery galleryid-36855 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/7-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1.jpg'><img decoding=\"async\" width=\"2000\" height=\"1200\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1-300x180.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1-1024x614.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1-768x461.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1-1536x922.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/6-1-600x360.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><strong>\u00bfYa est\u00e1is preparando viajes para el futuro?<\/strong><\/p>\n<blockquote><p>Kailey y yo haremos un peque\u00f1o viaje la semana que viene, pero esta vez yo me encargar\u00e9 de la ruta. No sale en el video, pero Kailey eligi\u00f3 la ruta, y fue realmente dura. Esta vez habr\u00e1 menos desnivel, m\u00e1s diversi\u00f3n y m\u00e1s bailes. Haremos un viaje de dos d\u00edas por el camino del <a href=\"http:\/\/www.omtm.cc\/deschutes-river-trail\" target=\"_blank\" rel=\"noopener\">r\u00edo Deschutes<\/a>. Si tenemos suerte, en mayo queremos hacer un viaje de cinco d\u00edas por Oregon. Esta vez con un equipo de c\u00e1mara para documentarlo.<\/p><\/blockquote>\n<p><strong>Un espacio para comentar lo que quieras.<\/strong><\/p>\n<blockquote><p>Todos estamos hechos de maneras distintas. Podr\u00eda dejar de comer, ir en bici y adelgazar, pero suena fatal. Prefiero comer saludablemente o no (a veces me gusta el helado), y a\u00fan as\u00ed poder ir en bici. Creo que la felicidad resuena en aquellos que andan en bici. Ellos lo entienden. Si alguien es feliz estando en forma y siendo el m\u00e1s r\u00e1pido, eso es genial. Como quieras ir en bici, hazlo. No estoy aqu\u00ed para juzgarte. A mi tambien me gusta ir r\u00e1pido cuando hay bajada, me encanta.<\/p>\n<p>Tambi\u00e9n, algunas de las mejores experiencias que he tenido sobre la bici son cuando me paro para hablar con la gente. Pararse a ayudar a alguien con una rueda pinchada o dando indicaciones. Creo que la gente que lleva tiempo andando en bici pueden llegar a pensar que est\u00e1n por encima del resto y que son los mejores. Puede ser bueno acordarse que un d\u00eda tambi\u00e9n fuiste un principiante y si alguien necesita ayuda, deber\u00edas parar a ayudarle. Nunca sabes lo que puedes llegar a aprender.<\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"All Bodies on Bikes | SHIMANO\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/JytAXpxmmQY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos d\u00edas, Shimano lanz\u00f3 el video All bodies on bikes, en la que Marley Blonsky y Kailey Kornhauser realizan<\/p>\n","protected":false},"author":12,"featured_media":30369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4079,3957],"tags":[4275,4071,4082,4461],"class_list":["post-36855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-entrevistas","tag-shimano-es","tag-cycling-videos-es","tag-bikepacking-es","tag-adventure-cycling-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marley Blonsky: All bodies on bikes - RAW Cycling Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marley Blonsky: All bodies on bikes\" \/>\n<meta property=\"og:description\" content=\"Hace unos d\u00edas, Shimano lanz\u00f3 el video All bodies on bikes, en la que Marley Blonsky y Kailey Kornhauser realizan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/\" \/>\n<meta property=\"og:site_name\" content=\"RAW Cycling Magazine\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/rawcyclingmag\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-26T20:30:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2021\/04\/cover1.jpg\" \/>\n<meta name=\"author\" content=\"Pol Sope\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2021\/04\/cover1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:site\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pol Sope\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/\"},\"author\":{\"name\":\"Pol Sope\u00f1a\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483\"},\"headline\":\"Marley Blonsky: All bodies on bikes\",\"datePublished\":\"2021-04-26T20:30:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/\"},\"wordCount\":1643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg\",\"keywords\":[\"shimano\",\"cycling videos\",\"bikepacking\",\"adventure cycling\"],\"articleSection\":[\"Destacado\",\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/\",\"name\":\"Marley Blonsky: All bodies on bikes - RAW Cycling Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg\",\"datePublished\":\"2021-04-26T20:30:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg\",\"width\":2000,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/rawcyclingmag.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marley Blonsky: All bodies on bikes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"name\":\"RAW Cycling Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\",\"name\":\"RAW Cycling Magazine\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"width\":300,\"height\":140,\"caption\":\"RAW Cycling Magazine\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/facebook.com\/rawcyclingmag\",\"https:\/\/x.com\/rawcyclingmag\",\"http:\/\/instagram.com\/rawcyclingmag\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483\",\"name\":\"Pol Sope\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g\",\"caption\":\"Pol Sope\u00f1a\"},\"description\":\"Apasionado de la bici y de la competici\u00f3n, Pol, siempre est\u00e1 preparado para una nueva aventura. Le encanta la sensaci\u00f3n de ponerse un dorsal y es un aut\u00e9ntico adicto al ciclocros. Passionate about bikes and racing, Pol is always ready for a new adventure. He loves the feeling of pinning a number and he is truly addicted to cyclocross.\",\"sameAs\":[\"https:\/\/www.instagram.com\/polsope\/\"],\"url\":\"https:\/\/rawcyclingmag.com\/es\/author\/pol\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marley Blonsky: All bodies on bikes - RAW Cycling Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/","og_locale":"es_ES","og_type":"article","og_title":"Marley Blonsky: All bodies on bikes","og_description":"Hace unos d\u00edas, Shimano lanz\u00f3 el video All bodies on bikes, en la que Marley Blonsky y Kailey Kornhauser realizan","og_url":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/","og_site_name":"RAW Cycling Magazine","article_publisher":"http:\/\/facebook.com\/rawcyclingmag","article_published_time":"2021-04-26T20:30:53+00:00","og_image":[{"url":"https:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2021\/04\/cover1.jpg","type":"","width":"","height":""}],"author":"Pol Sope\u00f1a","twitter_card":"summary_large_image","twitter_image":"https:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2021\/04\/cover1.jpg","twitter_creator":"@rawcyclingmag","twitter_site":"@rawcyclingmag","twitter_misc":{"Escrito por":"Pol Sope\u00f1a","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#article","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/"},"author":{"name":"Pol Sope\u00f1a","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483"},"headline":"Marley Blonsky: All bodies on bikes","datePublished":"2021-04-26T20:30:53+00:00","mainEntityOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/"},"wordCount":1643,"commentCount":0,"publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg","keywords":["shimano","cycling videos","bikepacking","adventure cycling"],"articleSection":["Destacado","Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/","url":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/","name":"Marley Blonsky: All bodies on bikes - RAW Cycling Magazine","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg","datePublished":"2021-04-26T20:30:53+00:00","breadcrumb":{"@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#primaryimage","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2021\/04\/cover1.jpg","width":2000,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/rawcyclingmag.com\/es\/marley-blonsky-all-bodies-on-bikes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rawcyclingmag.com\/es\/"},{"@type":"ListItem","position":2,"name":"Marley Blonsky: All bodies on bikes"}]},{"@type":"WebSite","@id":"https:\/\/rawcyclingmag.com\/es\/#website","url":"https:\/\/rawcyclingmag.com\/es\/","name":"RAW Cycling Magazine","description":"","publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rawcyclingmag.com\/es\/#organization","name":"RAW Cycling Magazine","url":"https:\/\/rawcyclingmag.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","width":300,"height":140,"caption":"RAW Cycling Magazine"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/rawcyclingmag","https:\/\/x.com\/rawcyclingmag","http:\/\/instagram.com\/rawcyclingmag"]},{"@type":"Person","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/d5fdfa78f8ba97937cc550dd6e507483","name":"Pol Sope\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2131adfac3a750a08f687088feb1782f81343b995246e46197c8e480c1c8695e?s=96&d=mm&r=g","caption":"Pol Sope\u00f1a"},"description":"Apasionado de la bici y de la competici\u00f3n, Pol, siempre est\u00e1 preparado para una nueva aventura. Le encanta la sensaci\u00f3n de ponerse un dorsal y es un aut\u00e9ntico adicto al ciclocros. Passionate about bikes and racing, Pol is always ready for a new adventure. He loves the feeling of pinning a number and he is truly addicted to cyclocross.","sameAs":["https:\/\/www.instagram.com\/polsope\/"],"url":"https:\/\/rawcyclingmag.com\/es\/author\/pol\/"}]}},"_links":{"self":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/36855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/comments?post=36855"}],"version-history":[{"count":0,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/36855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media\/30369"}],"wp:attachment":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media?parent=36855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/categories?post=36855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/tags?post=36855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}