{"id":36693,"date":"2020-04-27T22:43:16","date_gmt":"2020-04-27T20:43:16","guid":{"rendered":"https:\/\/raw.ecoolabs.com\/chas-christiansen-alocadamente-sensato\/"},"modified":"2020-04-27T22:43:16","modified_gmt":"2020-04-27T20:43:16","slug":"chas-christiansen-alocadamente-sensato","status":"publish","type":"post","link":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/","title":{"rendered":"Chas Christiansen, alocadamente sensato"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Dicen que so\u00f1ar es gratis, y durante estos d\u00edas (de confinamiento) es inevitable no hacerlo. Cerrar los ojos e imaginar futuros viajes es una buena opci\u00f3n, pero tambi\u00e9n podemos recurrir a los recuerdos, volver a esos d\u00edas de gloria repletos de viajes y competiciones alrededor del mundo, y rememorar ser parte de esa gran comunidad ciclista con la que compartimos un sinf\u00edn de momentos y aventuras. Para nosotros esto se remonta a los a\u00f1os de m\u00e1ximo esplendor del pi\u00f1\u00f3n fijo, momento que muchos recordar\u00e1n con mucha melancol\u00eda y que, en nuestro caso, represent\u00f3 el comienzo de RAW como proyecto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante esos a\u00f1os, hubo grandes referentes a nivel mundial que claramente dejaron huella en la escena fixed. Podr\u00edamos nombrar a muchos de ellos pero, en esta ocasi\u00f3n, hemos tenido la oportunidad de entrevistar a <\/span><a href=\"https:\/\/www.instagram.com\/notchas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Chas Christiansen<\/span><\/a><span style=\"font-weight: 400;\">, uno de los riders m\u00e1s carism\u00e1ticos, competitivos y con m\u00e1s recorrido en lo que a ciclismo urbano se refiere. Chas, a d\u00eda de hoy, sigue estando en activo y presente en multitud de carreras y eventos a nivel internacional, fiel a su estilo de vida y sin dejar de coleccionar nuevas aventuras. Al hablar con \u00e9l, tuvimos la posibilidad de conocer de primera mano un poco m\u00e1s acerca de su historia y trayectoria.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Mess Life<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Corr\u00eda el a\u00f1o 2005 aproximadamente, Christiansen viv\u00eda en Portland y combinaba su trabajo como cocinero, con el de hacer camisetas en un estudio de impresi\u00f3n. Utilizaba una bicicleta de CX para ir y venir del trabajo y, en uno de esos trayectos, un d\u00eda, se cruz\u00f3 con unos chicos que iban en bici de pi\u00f1\u00f3n fijo (cuando a\u00fan no sab\u00eda muy bien qu\u00e9 era). Tiempo m\u00e1s tarde, le invitaron a una carrera que se celebraba en la ciudad (<\/span><i><span style=\"font-weight: 400;\">alleycat<\/span><\/i><span style=\"font-weight: 400;\">) y empez\u00f3 a adentrarse en ese mundillo. Y as\u00ed, al cabo de un tiempo, decidi\u00f3 montarse su primera bici de pi\u00f1\u00f3n fijo transformando una antigua bici de carretera.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Poco a poco fue conociendo m\u00e1s acerca de la escena, hizo algunos amigos dentro de la comunidad y descubri\u00f3 que la mayor\u00eda de participantes de estas carreras eran bicimensajeros. Un d\u00eda, uno de ellos, propuso traspasarle su compa\u00f1\u00eda de mensajer\u00eda y, pese a que ganar\u00eda menos dinero y no ser\u00eda f\u00e1cil salir adelante, decidi\u00f3 probar.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cTrabajar como mensajero era una opci\u00f3n, no una necesidad. Cuando yo compet\u00eda en <\/span><i><span style=\"font-weight: 400;\">alleycats <\/span><\/i><span style=\"font-weight: 400;\">la mayor\u00eda de la gente era <\/span><i><span style=\"font-weight: 400;\">bike messenger<\/span><\/i><span style=\"font-weight: 400;\"> y parec\u00eda un trabajo guay. En aquella \u00e9poca yo trabajaba como cocinero.\u201d<\/span><\/p><\/blockquote>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-36693 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o.jpg'><img decoding=\"async\" width=\"1334\" height=\"2000\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o.jpg 1334w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o-683x1024.jpg 683w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o-768x1151.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o-1025x1536.jpg 1025w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/9338845930_1fc0982c18_o-600x900.jpg 600w\" sizes=\"(max-width: 1334px) 100vw, 1334px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1.jpg'><img decoding=\"async\" width=\"1334\" height=\"2000\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1.jpg 1334w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1-683x1024.jpg 683w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1-768x1151.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1-1025x1536.jpg 1025w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/15546970745_72698c95f5_h-1-600x900.jpg 600w\" sizes=\"(max-width: 1334px) 100vw, 1334px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b.jpg'><img decoding=\"async\" width=\"1334\" height=\"2000\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b.jpg 1334w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b-200x300.jpg 200w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b-683x1024.jpg 683w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b-768x1151.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b-1025x1536.jpg 1025w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/11542988905_b9e24e82fe_b-600x900.jpg 600w\" sizes=\"(max-width: 1334px) 100vw, 1334px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><span style=\"font-weight: 400;\">En 2009, despu\u00e9s de varios a\u00f1os de experiencia en el sector, Chas y un amigo decidieron crear <\/span><a href=\"https:\/\/www.instagram.com\/tcbcourier\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">TCB Courier<\/span><\/a><span style=\"font-weight: 400;\"> (<\/span><i><span style=\"font-weight: 400;\">Taking Care of Business<\/span><\/i><span style=\"font-weight: 400;\">). Un peque\u00f1o proyecto nada ambicioso pero que, despu\u00e9s de duros a\u00f1os de trabajo y esfuerzo, creci\u00f3 y consigui\u00f3 labrarse una reputaci\u00f3n entre los negocios de mensajer\u00eda de San Francisco, llegando a cubrir m\u00e1s de 700 env\u00edos al d\u00eda.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cDurante los primeros 4 a\u00f1os de TCB, la empresa era mi casa y, mi habitaci\u00f3n, y, finalmente, conseguimos un local donde instalarnos.\u201d<\/span><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"TCB COURIER 5 YEAR ANNIVERSARY\" src=\"https:\/\/player.vimeo.com\/video\/107521652?dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe><\/p>\n<h3><span style=\"font-weight: 400;\">Mash SF<\/span><\/h3>\n<p><a href=\"https:\/\/www.mashsf.com\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Mash SF<\/span><\/a><span style=\"font-weight: 400;\"> ha sido uno de los grandes referentes en el mundo del pi\u00f1\u00f3n fijo, mostrando al mundo entero la parte m\u00e1s alucinante de esta modalidad de ciclismo urbano, deleit\u00e1ndonos con una imagen de marca muy cuidada, una gran comunicaci\u00f3n en las redes sociales, los mejores trucos encima de una bici habidos y por haber, y unos v\u00eddeos de infarto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La famosa tienda de San Francisco abr\u00eda sus puertas en 2011 y fue en 2013 cuando Chas entraba a formar parte de la <\/span><a href=\"https:\/\/www.mashsf.com\/team-member\/chas\" target=\"_blank\" rel=\"noopener noreferrer\"><i><span style=\"font-weight: 400;\">crew<\/span><\/i><span style=\"font-weight: 400;\"> oficial de Mash SF<\/span><\/a><span style=\"font-weight: 400;\">. La f\u00f3rmula era infalible, encajaba a la perfecci\u00f3n junto al resto del equipo y estimulaba a\u00fan m\u00e1s la creatividad interminable de Mike Martin (creador de Mash SF) y de <\/span><a href=\"https:\/\/www.martinptr.com\/mashsf\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Martin Bustamente<\/span><\/a><span style=\"font-weight: 400;\"> (<\/span><i><span style=\"font-weight: 400;\">cameraman<\/span><\/i><span style=\"font-weight: 400;\"> de la mayor\u00eda de v\u00eddeos oficiales de la marca).<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cMike Martin siempre ha sido como un padre para todos los que form\u00e1bamos el equipo. \u00c9l quer\u00eda lo mejor para todos nosotros, siempre buscaba patrocinadores para ayudarnos durante los viajes y competiciones y, al mismo tiempo, quer\u00eda crear productos interesantes y con estilo para la escena fixed, como camisetas, peque\u00f1os componentes, cuadros de bicis, etc. Hacer buen material y salir a probarlos.\u201d<\/span><\/p><\/blockquote>\n<p><a href=\"http:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-11168\" src=\"http:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094.jpg 1920w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/DSC04866-22921610094-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Para muchos de los chicos del equipo, Mash ha sido como un trampol\u00edn en sus carreras profesionales. Les di\u00f3 una oportunidad de viajar, de crecer, de formar parte de un proyecto con gran repercusi\u00f3n, de competir en las mejores carreras a nivel mundial y de vivir nuevas experiencias. Algunos de ellos han dado el salto al ciclismo profesional, y a otros, como es el caso de Christiansen, les ha servido para seguir una trayectoria vinculada de pleno al ciclismo consiguiendo importantes <\/span><i><span style=\"font-weight: 400;\">sponsors<\/span><\/i><span style=\"font-weight: 400;\"> que creen en \u00e9l y le apoyan en todo lo que hace.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cPara m\u00ed Mash es donde estoy hoy. Mucho de lo que hago ahora es porque Mash estuvo ah\u00ed para apoyarme en su debido momento. Fue algo as\u00ed como <\/span><i><span style=\"font-weight: 400;\">\u201cvive tu vida y divi\u00e9rtete\u201d<\/span><\/i><span style=\"font-weight: 400;\">, no hubo nunca presi\u00f3n por ganar una carrera o hacer una buena sesi\u00f3n de fotos&#8230; Solo ten\u00edas que presentarte, divertirte, y competir al m\u00e1ximo.\u201d<\/span><\/p><\/blockquote>\n<p>https:\/\/vimeo.com\/177480086<\/p>\n<p><span style=\"font-weight: 400;\">Durante su paso por Mash, el papel de Chas no solo se reduc\u00eda a ser <\/span><i><span style=\"font-weight: 400;\">rider<\/span><\/i><span style=\"font-weight: 400;\"> del equipo, sino que tambi\u00e9n ayudaba a Mike y a los patrocinadores con el desarrollo y testeo de nuevos productos. Uno de los mayores ejemplos fue la colaboraci\u00f3n con <\/span><a href=\"https:\/\/cinelli.it\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Cinelli<\/span><\/a><span style=\"font-weight: 400;\"> y la creaci\u00f3n del famoso modelo Parallax de la marca italiana. Cada 3 o 4 meses recib\u00edan un prototipo que Chas se encargaba personalmente de probar y proponer ajustes y modificaciones para ir puliendo el dise\u00f1o y conseguir un mejor resultado. Tanto para Cinelli como para Mash y, en especial Chas, todo este proceso fue una gran experiencia y aprendizaje.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Racing spirit<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">No importa la disciplina, el terreno o la bicicleta, a Chas Christiansen le encanta la competici\u00f3n y as\u00ed lo ha demostrado en todos estos a\u00f1os. Lo hemos visto en <\/span><i><span style=\"font-weight: 400;\">alleycats<\/span><\/i><span style=\"font-weight: 400;\">, en campeonatos mundiales de bicimensajeros, en criteriums de pi\u00f1\u00f3n fijo, en carreras de ciclocross, tracklocross, gravel y, ahora tambi\u00e9n, probando la modalidad de ultradistancia. Es una persona competitiva, y entrena para mantener una buena forma f\u00edsica y rendimiento pero, por encima de todo, lo que m\u00e1s le gusta es disfrutar y vivir nuevas y grandes experiencias.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cMi parte favorita de las carreras es el momento de la salida, cuando te olvidas de todo y ya solo te centras en correr al m\u00e1ximo, sin importar la disciplina que sea.\u201d<\/span><\/p><\/blockquote>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-36693 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1684-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A3359-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/77A1681-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><span style=\"font-weight: 400;\">Mientras convers\u00e1bamos con \u00e9l, recordamos su paso por el <a href=\"https:\/\/redhookcrit.com\/history\/rhc-brooklyn-no-8\/\" target=\"_blank\" rel=\"noopener noreferrer\">RHC Brooklyn No.8<\/a> en la que pudimos ver a un Chas haciendo una carrera impecable, consiguiendo abrir hueco con el pelot\u00f3n de cabeza tras un gran ataque, disfrutando, sufriendo, pero sin perder la sonrisa de su cara. Finalmente, tras verse involucrado en una ca\u00edda, se hizo con el premio <\/span><i><span style=\"font-weight: 400;\">Top Antagonist<\/span><\/i><span style=\"font-weight: 400;\"> de la noche.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cPosiblemente, mis disciplinas favoritas sean los <\/span><i><span style=\"font-weight: 400;\">alleycats <\/span><\/i><span style=\"font-weight: 400;\">y criteriums, pero cada vez estoy disfrutando m\u00e1s en gravel y ultradistancia, aunque para esta \u00faltima te debes preparar la carrera de otra manera.\u201d<\/span><\/p><\/blockquote>\n<h3><span style=\"font-weight: 400;\">El Chas m\u00e1s personal<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Actualmente, Chas se encuentra en un punto de su vida algo m\u00e1s relajado. Despu\u00e9s de que la etapa en TCB finalizara, comenz\u00f3 una relaci\u00f3n con su actual pareja, se mudaron a Oakland y ahora viven en familia junto al hijo de ella, algo que a\u00f1os atr\u00e1s seguramente nunca se hubiese planteado.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cEstuve en contra de este estilo durante mucho tiempo, pero un d\u00eda me di cuenta que necesitaba reducir la velocidad y no vivir siempre como <\/span><i><span style=\"font-weight: 400;\">Peter Pan<\/span><\/i><span style=\"font-weight: 400;\">. Y el cambio ha sido bueno. Antes la vida siempre era una fiesta, pero uno envejece y ese plan no es sostenible, as\u00ed que estoy tratando de encontrar un ritmo de vida que me permite viajar, tener una vida emocionante y, por otro lado, tener una vida hogare\u00f1a que sea tranquila.\u201d<\/span><\/p><\/blockquote>\n<p><a href=\"http:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-11166\" src=\"http:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705.jpg\" alt=\"\" width=\"2000\" height=\"1334\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2705-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">A nivel profesional tambi\u00e9n su vida ha dado un giro. Pese a que nunca ha sido muy partidario de vivir de los patrocinios, se ha dado cuenta que puede compaginar el ayudar a las marcas que le apoyan y le brindan oportunidades para crecer juntos, con los viajes y aventuras de los que a d\u00eda de hoy sigue disfrutando.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n invierte m\u00e1s tiempo en leer y trabajar en su aspecto m\u00e1s creativo, el cual le ha acompa\u00f1ado durante toda su vida y ha intentado plasmar en todos los proyectos en los que ha estado involucrado, ya sea <\/span><a href=\"http:\/\/www.notchas.com\/projects\"><span style=\"font-weight: 400;\">dise\u00f1ando camisetas, logotipos, posters, o personalizando componentes e, incluso, bicis completas<\/span><\/a><span style=\"font-weight: 400;\">. De hecho, y como consecuencia de ello, hace un tiempo decidi\u00f3 crear <\/span><span style=\"font-weight: 400;\">notchas.com<\/span><span style=\"font-weight: 400;\"> d\u00f3nde da un espacio a algunas de sus creaciones.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cNo le daba mucha importancia a mis dise\u00f1os, pero vi que a la gente le encantaba. La idea empez\u00f3 a crecer y me encant\u00f3. Da un poco de miedo porque el arte es una de mis pasiones, pero lo estoy haciendo como un trabajo y quiero disfrutarlo. Ya veremos en el futuro, porque es dif\u00edcil mantener una pasi\u00f3n por el arte que adem\u00e1s sea un trabajo.\u201d<\/span><\/p><\/blockquote>\n<h3><span style=\"font-weight: 400;\">Pandemia mundial<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Inevitablemente, en nuestra charla con Chas sali\u00f3 el tema de la epidemia del COVID-19. Tras preguntarle como lo estaba viviendo, nos coment\u00f3 que se centra en los peque\u00f1os aspectos del d\u00eda a d\u00eda manteniendo una mente positiva.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cPor suerte estoy con mi familia y puedo interactuar con ellos a diario. Intento mantenerme positivo, tratar de hacer esas peque\u00f1as cosas que me hacen feliz todos los d\u00edas, y evito pensar en todo lo que est\u00e1 sucediendo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Intentamos mantenernos activos y hacer ejercicio, aunque por otro lado, creo que es importante tomarse estos d\u00edas con tranquilidad y disfrutando tambi\u00e9n de momentos de relajaci\u00f3n como si fuesen unas peque\u00f1as vacaciones. No me pongo el despertador, incluso como pizza tres veces por semana y, de vez en cuando, mi novia y yo nos tomamos unas Margaritas.\u201d<\/span><\/p><\/blockquote>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-36693 gallery-columns-4 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC2357-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180920-_DSC3288-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180912-_DSC9601-2-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180915-_DSC2887-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180922-_DSC3665-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines-600x400.jpg 600w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/jonathan-hines-272x182.jpg 272w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Fotos de: <a href=\"http:\/\/instagram.com\/brazodehierro\" target=\"_blank\" rel=\"noopener noreferrer\">Brazo de Hierro<\/a>, <a href=\"http:\/\/instagram.com\/samisauri\" target=\"_blank\" rel=\"noopener noreferrer\">Sami Sauri<\/a>, <a href=\"http:\/\/instagram.com\/tdtorre\" target=\"_blank\" rel=\"noopener noreferrer\">Toni de la Torre<\/a>, <a href=\"https:\/\/www.instagram.com\/jonnyhinesphoto\" target=\"_blank\" rel=\"noopener noreferrer\">Jonathan Hines<\/a>, <a href=\"https:\/\/www.instagram.com\/johndanielreiss\/\" target=\"_blank\" rel=\"noopener noreferrer\">John Daniel Reiss<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dicen que so\u00f1ar es gratis, y durante estos d\u00edas (de confinamiento) es inevitable no hacerlo. Cerrar los ojos e imaginar<\/p>\n","protected":false},"author":9,"featured_media":28984,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4079,3957],"tags":[4430,4463,4284],"class_list":["post-36693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-entrevistas","tag-sram-es","tag-sami-sauri-es","tag-ultra-distance-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chas Christiansen, alocadamente sensato - RAW Cycling Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chas Christiansen, alocadamente sensato\" \/>\n<meta property=\"og:description\" content=\"Dicen que so\u00f1ar es gratis, y durante estos d\u00edas (de confinamiento) es inevitable no hacerlo. Cerrar los ojos e imaginar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/\" \/>\n<meta property=\"og:site_name\" content=\"RAW Cycling Magazine\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/rawcyclingmag\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T20:43:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg\" \/>\n<meta name=\"author\" content=\"Toni de la Torre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:site\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toni de la Torre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/\"},\"author\":{\"name\":\"Toni de la Torre\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/47434e9e6c5cdbe8ac2e539762af7684\"},\"headline\":\"Chas Christiansen, alocadamente sensato\",\"datePublished\":\"2020-04-27T20:43:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/\"},\"wordCount\":1776,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg\",\"keywords\":[\"SRAM\",\"sami sauri\",\"ultra distance\"],\"articleSection\":[\"Destacado\",\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/\",\"name\":\"Chas Christiansen, alocadamente sensato - RAW Cycling Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg\",\"datePublished\":\"2020-04-27T20:43:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg\",\"width\":2000,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/rawcyclingmag.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chas Christiansen, alocadamente sensato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"name\":\"RAW Cycling Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\",\"name\":\"RAW Cycling Magazine\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"width\":300,\"height\":140,\"caption\":\"RAW Cycling Magazine\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/facebook.com\/rawcyclingmag\",\"https:\/\/x.com\/rawcyclingmag\",\"http:\/\/instagram.com\/rawcyclingmag\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/47434e9e6c5cdbe8ac2e539762af7684\",\"name\":\"Toni de la Torre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c407c6850ed8959f50b8fce5fbedc127d5be409844c8889160020e576331fec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c407c6850ed8959f50b8fce5fbedc127d5be409844c8889160020e576331fec?s=96&d=mm&r=g\",\"caption\":\"Toni de la Torre\"},\"description\":\"Es el motor y el combustible de todos los proyectos que crea, desarrolla y finaliza. Toni es cofundador del magazine, y es met\u00f3dico y trabajador como ninguno, parece tener una extra\u00f1a adicci\u00f3n a implicarse en proyectos ciclistas. He is the engine and the fuel of each of the projects he creates, develops, and completes. Toni is the co-founder of the magazine, he is methodical and worker as few, and he seems to have a strange addiction to being involved in cycling projects.\",\"sameAs\":[\"https:\/\/www.instagram.com\/tdtorre\/\"],\"url\":\"https:\/\/rawcyclingmag.com\/es\/author\/toni\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chas Christiansen, alocadamente sensato - RAW Cycling Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/","og_locale":"es_ES","og_type":"article","og_title":"Chas Christiansen, alocadamente sensato","og_description":"Dicen que so\u00f1ar es gratis, y durante estos d\u00edas (de confinamiento) es inevitable no hacerlo. Cerrar los ojos e imaginar","og_url":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/","og_site_name":"RAW Cycling Magazine","article_publisher":"http:\/\/facebook.com\/rawcyclingmag","article_published_time":"2020-04-27T20:43:16+00:00","og_image":[{"url":"http:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg","type":"","width":"","height":""}],"author":"Toni de la Torre","twitter_card":"summary_large_image","twitter_image":"http:\/\/raw.ecoolabs.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg","twitter_creator":"@rawcyclingmag","twitter_site":"@rawcyclingmag","twitter_misc":{"Escrito por":"Toni de la Torre","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#article","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/"},"author":{"name":"Toni de la Torre","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/47434e9e6c5cdbe8ac2e539762af7684"},"headline":"Chas Christiansen, alocadamente sensato","datePublished":"2020-04-27T20:43:16+00:00","mainEntityOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/"},"wordCount":1776,"commentCount":0,"publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg","keywords":["SRAM","sami sauri","ultra distance"],"articleSection":["Destacado","Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/","url":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/","name":"Chas Christiansen, alocadamente sensato - RAW Cycling Magazine","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg","datePublished":"2020-04-27T20:43:16+00:00","breadcrumb":{"@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#primaryimage","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2020\/04\/20180917-_DSC3030.jpg","width":2000,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/rawcyclingmag.com\/es\/chas-christiansen-alocadamente-sensato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rawcyclingmag.com\/es\/"},{"@type":"ListItem","position":2,"name":"Chas Christiansen, alocadamente sensato"}]},{"@type":"WebSite","@id":"https:\/\/rawcyclingmag.com\/es\/#website","url":"https:\/\/rawcyclingmag.com\/es\/","name":"RAW Cycling Magazine","description":"","publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rawcyclingmag.com\/es\/#organization","name":"RAW Cycling Magazine","url":"https:\/\/rawcyclingmag.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","width":300,"height":140,"caption":"RAW Cycling Magazine"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/rawcyclingmag","https:\/\/x.com\/rawcyclingmag","http:\/\/instagram.com\/rawcyclingmag"]},{"@type":"Person","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/47434e9e6c5cdbe8ac2e539762af7684","name":"Toni de la Torre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c407c6850ed8959f50b8fce5fbedc127d5be409844c8889160020e576331fec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c407c6850ed8959f50b8fce5fbedc127d5be409844c8889160020e576331fec?s=96&d=mm&r=g","caption":"Toni de la Torre"},"description":"Es el motor y el combustible de todos los proyectos que crea, desarrolla y finaliza. Toni es cofundador del magazine, y es met\u00f3dico y trabajador como ninguno, parece tener una extra\u00f1a adicci\u00f3n a implicarse en proyectos ciclistas. He is the engine and the fuel of each of the projects he creates, develops, and completes. Toni is the co-founder of the magazine, he is methodical and worker as few, and he seems to have a strange addiction to being involved in cycling projects.","sameAs":["https:\/\/www.instagram.com\/tdtorre\/"],"url":"https:\/\/rawcyclingmag.com\/es\/author\/toni\/"}]}},"_links":{"self":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/36693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/comments?post=36693"}],"version-history":[{"count":0,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/36693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media\/28984"}],"wp:attachment":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media?parent=36693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/categories?post=36693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/tags?post=36693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}