{"id":36631,"date":"2019-11-20T21:30:31","date_gmt":"2019-11-20T20:30:31","guid":{"rendered":"https:\/\/raw.ecoolabs.com\/lael-wilcox-i-just-want-to-ride\/"},"modified":"2019-11-20T21:30:31","modified_gmt":"2019-11-20T20:30:31","slug":"lael-wilcox-i-just-want-to-ride","status":"publish","type":"post","link":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/","title":{"rendered":"Lael Wilcox: I just want to ride"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A ra\u00edz del lanzamiento al p\u00fablico de <a href=\"https:\/\/www.youtube.com\/watch?v=AEEGIt6FC34\" target=\"_blank\" rel=\"noopener noreferrer\">\u201cI Just Want to Ride\u201d<\/a>, la pel\u00edcula que narra la historia de <a href=\"https:\/\/laelwilcox.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lael Wilcox<\/a> mientras compite en la edici\u00f3n de este a\u00f1o del <a href=\"https:\/\/tourdivide.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tour Divide<\/a>, aprovechamos la ocasi\u00f3n para sacar a la luz la conversaci\u00f3n que tuvimos con ella al acabar la <a href=\"http:\/\/rawcyclingmag.com\/silk-road-mountain-race\/\" target=\"_blank\" rel=\"noopener noreferrer\">Silk Road Mountain Race<\/a>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lael es una de las personas m\u00e1s especiales e inspiradoras que conocemos, y descubrir\u00e9is por qu\u00e9 tras leer sus respuestas.<\/span><\/p>\n<p><b>\u00bfQui\u00e9n es Lael Wilcox?<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Soy una mujer de 33 a\u00f1os procedente de Anchorage, Alaska. No empec\u00e9 a montar en bicicleta hasta los 20 a\u00f1os para ir y volver del trabajo, siendo 6 km en ambas direcciones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un a\u00f1o despu\u00e9s, utilizaba la bicicleta para desplazarme hasta la ciudad m\u00e1s cercana, y dos a\u00f1os despu\u00e9s comenc\u00e9 a recorrer el pa\u00eds, y luego llegaron los viajes alrededor del mundo. Sol\u00eda trabajar durante seis meses como camarera en un restaurante y ahorrar todo lo posible para poder viajar con mi bicicleta el resto del a\u00f1o. Durante una estancia en Israel en la primavera de 2015, vi que una carrera de autosuficiencia de 1.400 km llamada Holyland Challenge ten\u00eda lugar durante los d\u00edas que estaba all\u00ed. Decid\u00ed apuntarme por diversi\u00f3n y para vivir nuevas experiencias. Yo era la \u00fanica mujer compitiendo, y lo hice con una bici barata de cicloturismo, con ocho marchas, cuadro de acero y suspensi\u00f3n delantera. Llevaba pedales de plataforma, bambas de correr y una camiseta de algod\u00f3n. Antes de finalizar el primer d\u00eda, ya lideraba la carrera por m\u00e1s de 40 km. Todo el mundo se qued\u00f3 sorprendido, incluso yo. Me di cuenta de que eso era algo que realmente pod\u00eda hacer, y algo que se me daba bien.&#8221;<\/span><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-10008\" src=\"http:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_001.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_001.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_001-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_001-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_001-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_001-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_001-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><b>\u00bfQu\u00e9 es montar en bicicleta para t\u00ed?<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;La bici significa muchas cosas para m\u00ed; es un medio de transporte, y una forma de ejercitarme, divertirme y ver el mundo. Es un mundo competitivo pero tambi\u00e9n puede ser relajante. Es definitivamente algo que quiero compartir con los dem\u00e1s. Soy la encargada de un programa de mentorizaci\u00f3n para chicas ciclistas llamado Anchorage GRIT. Trabajamos con chicas de 12 y 13 a\u00f1os con pocos recursos. Al principio del programa siempre les resulta dif\u00edcil hacer 12 km, pero seis semanas despu\u00e9s recorren 100 km desde su escuela hacia los entornos salvajes de Alaska. Es incre\u00edble ver su transformaci\u00f3n y su habilidad para cumplir retos. Anchorage es la ciudad donde nac\u00ed y me hubiera gustado vivir algo as\u00ed cuando era joven. Al fin y al cabo no se trata de ser la mejor atleta, sino de hacerlo lo mejor que puedas.&#8221;<\/span><\/p><\/blockquote>\n<p><b>\u00bfCu\u00e1ndo comenzaste con las carreras de ultra distancia?<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Tras la carrera en Israel, volv\u00ed a casa, me compr\u00e9 una bici nueva (una Specialized Stumpjumper de carbono con suspensi\u00f3n delantera) y, una semana despu\u00e9s comenc\u00e9 mi viaje de 3.400 km de longitud entre Anchorage hasta Banff, Alberta (Canad\u00e1) para el inicio del Tour Divide.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Era mi primera ruta larga en bicicleta en solitario y la complet\u00e9 en 19 d\u00edas. Yo soy de Alaska, pero nunca hab\u00eda recorrido la carretera que atraviesa Canad\u00e1. Siempre hab\u00eda volado hasta Seattle, en Washington. Fue realmente incre\u00edble ver todas esas tierras en Yuk\u00f3n sentada en mi bicicleta. Es una zona muy remota. A menudo, el \u00fanico tipo de comida disponible es de una gasolinera, y \u00fanicamente las encuentras cada 150 km, m\u00e1s o menos. Al terminar la ruta, descans\u00e9 durante una semana en Banff y despu\u00e9s comenc\u00e9 el Tour Divide. Rebaj\u00e9 dos d\u00edas el r\u00e9cord femenino, dej\u00e1ndolo en 17 d\u00edas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero esa no fue mi primera carrera. La primera toma de contacto con las carreras de ultra distancia fue una contrarreloj de 600 km durante el verano de 2014. Ese verano utilizaba mis dos d\u00edas libres de trabajo semanales para montar en bici tanto como pudiera. Al final del verano, mi mejor amiga Christina Grande me pregunt\u00f3 si correr\u00eda la Fireweed 400, una carrera de autosuficiencia hasta Valdez (Alaska) y vuelta, con una longitud total de 600 km. Para el evento era necesario contar con un veh\u00edculo de asistencia. Christina dijo que ella podr\u00eda darme apoyo, y encontramos a otro amigo que har\u00eda de mec\u00e1nico. Realmente no ten\u00eda ni idea de si iba a ser capaz de completar la distancia total antes del corte, que eran 32 horas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cog\u00ed prestada la bici de carretera de mi madre y fui a por ello. Acab\u00e9 con un tiempo de 27 horas, siendo la primera mujer y la segunda en la general, 12 minutos detr\u00e1s de un hombre que compiti\u00f3 con un bicicleta reclinada. La mayor sorpresa fue que no acab\u00e9 exhausta. Sab\u00eda que pod\u00eda llegar m\u00e1s lejos.&#8221;<\/span><\/p><\/blockquote>\n<p><b>\u00bfQu\u00e9 nos puedes contar acerca de tu primera carrera de ultra distancia?<\/b><\/p>\n<blockquote><p>&#8220;Mi primera carrera fue una contrarreloj de 600 km en carretera, en 2014. Durante ese verano, me tom\u00e9 dos d\u00edas libres de mi trabajo y viaj\u00e9 lo m\u00e1s lejos que pude. Al final del verano, mi mejor amiga, Christina Grande, me pregunt\u00f3 si me atrever\u00eda a correr la Fireweed 400, una carrera de carretera de 400 millas (600 km) a Valdez (Alaska) y vuelta. Para esta carrera, se requiere que tengas un veh\u00edculo de apoyo. Christina dijo que ella se ofrec\u00eda como voluntaria y encontramos a otro amigo que hizo de mec\u00e1nico. No ten\u00eda ni idea si podr\u00eda completar la distancia antes del l\u00edmite de 32 horas.<\/p>\n<p>Cog\u00ed prestada la bicicleta de carretera de mi madre y me inscrib\u00ed. Termin\u00e9 el recorrido completo en 27 horas. Fui la primera mujer, y la \u00fanica persona que me adelant\u00f3 fue un hombre en una bicicleta reclinada. Termin\u00f3 12 minutos m\u00e1s r\u00e1pido que yo. La mayor sorpresa fue que, al final, no me sent\u00eda tan cansada como pensaba. Sab\u00eda que a\u00fan pod\u00eda ir m\u00e1s lejos &#8220;.<\/p><\/blockquote>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-36631 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007.jpg'><img decoding=\"async\" width=\"2000\" height=\"1331\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007-1024x681.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007-768x511.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007-1536x1022.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_007-600x399.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002.jpg'><img decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002-1024x683.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002-1536x1025.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_002-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><b>H\u00e1blanos de algunos de los momentos m\u00e1s especiales de todos estos a\u00f1os, tus mejores resultados o tus carreras favoritas.<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;En 2016 gan\u00e9 la clasificaci\u00f3n general de la <a href=\"https:\/\/transambikerace.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Trans Am Bike Race<\/a>, una carrera de 6.800 km de autosuficiencia a trav\u00e9s de Estados Unidos, desde Oregon a Virginia. Atrap\u00e9 al lider la \u00faltima noche a las tres de la ma\u00f1ana con 210 km restantes. \u00a1Fue s\u00faper emocionante!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este tipo de carreras requieren mucha concentraci\u00f3n, y te obligan a tener un alto nivel de alerta durante m\u00e1s de dos semanas. Esto incluye falta de sue\u00f1o; normalmente duermo cuatro o cinco horas por noche. A pesar de todos los sacrificios, me encanta pasar todas esas horas en el exterior con mi bicicleta. Es incre\u00edble la sensaci\u00f3n de estar en sinton\u00eda con la naturaleza, es una experiencia muy enriquecedora.&#8221;<\/span><\/p><\/blockquote>\n<p><b>\u00bfCon qu\u00e9 adjetivo describir\u00edas este tipo de competiciones?<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Largas.&#8221;<\/span><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-10014\" src=\"http:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_002.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_002.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_002-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_002-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_002-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_002-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_002-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><b>\u00bfC\u00f3mo entrenas?<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Simplemente monto en bicicleta.&#8221;<\/span><\/p><\/blockquote>\n<p><b>SRMR: \u00bfQu\u00e9 nos puedes decir de esta carrera? \u00bfC\u00f3mo organizaste tu nutrici\u00f3n y descanso?\u00a0<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Kirguist\u00e1n es excepcionalmente bonito, con enormes monta\u00f1as pedregosas, praderas verdes, agua fresca y muchos lagos. Gran parte de la carrera fue por encima de los 3.000 metros de altitud, as\u00ed que vine un mes antes del inicio para poder reconocer algunas partes de la ruta, aclimatarme y aprender de la cultura local. Cre\u00ed que, ya que el viaje desde Alaska era tan ajetreado (m\u00e1s de treinta horas en avi\u00f3n), podr\u00eda pasar un tiempo extra en el pa\u00eds para conocerlo, y estoy muy agradecida de haberlo hecho.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las carreteras son realmente complicadas. Definitivamente necesitas una <\/span><i><span style=\"font-weight: 400;\">mountain bike <\/span><\/i><span style=\"font-weight: 400;\">con ruedas anchas para cruzar el territorio con \u00e9xito. Durante la carrera, nev\u00f3 m\u00e1s de la mitad de los d\u00edas. El tiempo era muy impredecible, ya que por ejemplo tres semanas antes estaba a 40\u00baC.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Me encanta montar en bici en solitario y en ning\u00fan momento me sent\u00ed sola, pero me gust\u00f3 estar en contacto con varios jinetes kirguises. Eran muy amigables y amables, y se sorprend\u00edan al verme. A veces, \u00a1me propon\u00edan cambiar mi bici por su caballo!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Generalmente com\u00eda encima de la bici. A veces, no hab\u00eda mucha comida de f\u00e1cil acceso. A menudo compraba unos cinco trozos de <\/span><i><span style=\"font-weight: 400;\">Piroshki<\/span><\/i><span style=\"font-weight: 400;\"> (pan frito relleno de patata) y un par de barritas Snickers, y eso era mi comida para el resto del d\u00eda. Si encontraba alguna tienda con yogurt bebible, me compraba uno bien grande antes de continuar. Hay agua fresca en la mayor\u00eda del pa\u00eds, as\u00ed que el agua no era un problema. De hecho creo que soy la \u00fanica participante que no la filtraba o purificaba; simplemente la beb\u00eda. I no enferm\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En tres de la noches me aloj\u00e9 en casas de hu\u00e9spedes, las otras noches dorm\u00ed en el exterior. Ten\u00eda un saco de dormir, un vivac y una colchoneta inflable. Tambi\u00e9n una chaqueta de plumas y unos pantalones. Me mantuve caliente y c\u00f3moda.&#8221;<\/span><\/p><\/blockquote>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-36631 gallery-columns-3 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Race_RugileKaladyte_002-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_004-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_011-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><b>\u00bfCu\u00e1l es la situaci\u00f3n de las mujeres en el ciclismo de ultra distancia?<\/b><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Creo que en el ciclismo de ultra resistencia las mujeres son igual de capaces que los hombres. La \u00fanica raz\u00f3n por la que no vemos a m\u00e1s mujeres ganando carreras es porque no hay muchas que participen. Este a\u00f1o en la SRMR, solo 9 de los 140 participantes eran mujeres. En cuanto a participaci\u00f3n, es un deporte dominado por los hombres, pero me gustar\u00eda que la cosa cambiara.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed que no dejes que nadie te diga qu\u00e9 puedes o no puedes hacer. Monta en bicicleta a tu manera y mira qu\u00e9 pasa. Quiz\u00e1s te sorprendes a ti misma.&#8221;<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">\u201cI Just Want to Ride\u201d <a href=\"https:\/\/www.youtube.com\/watch?v=AEEGIt6FC34\" target=\"_blank\" rel=\"noopener noreferrer\">ya est\u00e1 disponible en <\/a><\/span><span style=\"font-weight: 400;\">Youtube<\/span><span style=\"font-weight: 400;\">. \u00a1No esperes m\u00e1s y ves a verlo!<\/span><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-36631 gallery-columns-4 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006.jpg'><img decoding=\"async\" width=\"2000\" height=\"1331\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006-1024x681.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006-768x511.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006-1536x1022.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_006-600x399.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_010-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_006-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_001-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_013-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003.jpg'><img decoding=\"async\" width=\"2000\" height=\"1331\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003-1024x681.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003-768x511.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003-1536x1022.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_003-600x399.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005.jpg'><img decoding=\"async\" width=\"2000\" height=\"1331\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005-1024x681.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005-768x511.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005-1536x1022.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/Navad1000_RugileKaladyte_005-600x399.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004.jpg'><img decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004.jpg 2000w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004-300x200.jpg 300w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004-1024x682.jpg 1024w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004-768x512.jpg 768w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004-1536x1024.jpg 1536w, https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_TourDivide_RugileKaladyte_004-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Fotos de <a href=\"https:\/\/www.instagram.com\/rugilekaladyte\" target=\"_blank\" rel=\"noopener noreferrer\">Rue Kaladyte<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ra\u00edz del lanzamiento al p\u00fablico de \u201cI Just Want to Ride\u201d, la pel\u00edcula que narra la historia de Lael<\/p>\n","protected":false},"author":11,"featured_media":28455,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4079,3957],"tags":[4436,4285,4087,4058,4464],"class_list":["post-36631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-entrevistas","tag-cycling-adventures-es","tag-lael-wilcox-es","tag-women-cycling-es","tag-gravel-es","tag-silk-road-mountain-race-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lael Wilcox: I just want to ride - RAW Cycling Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lael Wilcox: I just want to ride\" \/>\n<meta property=\"og:description\" content=\"A ra\u00edz del lanzamiento al p\u00fablico de \u201cI Just Want to Ride\u201d, la pel\u00edcula que narra la historia de Lael\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/\" \/>\n<meta property=\"og:site_name\" content=\"RAW Cycling Magazine\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/rawcyclingmag\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-20T20:30:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Javi Angulo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:site\" content=\"@rawcyclingmag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javi Angulo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/\"},\"author\":{\"name\":\"Javi Angulo\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2\"},\"headline\":\"Lael Wilcox: I just want to ride\",\"datePublished\":\"2019-11-20T20:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/\"},\"wordCount\":1675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg\",\"keywords\":[\"cycling adventures\",\"lael wilcox\",\"women cycling\",\"gravel\",\"silk road mountain race\"],\"articleSection\":[\"Destacado\",\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/\",\"name\":\"Lael Wilcox: I just want to ride - RAW Cycling Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg\",\"datePublished\":\"2019-11-20T20:30:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/rawcyclingmag.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lael Wilcox: I just want to ride\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#website\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"name\":\"RAW Cycling Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#organization\",\"name\":\"RAW Cycling Magazine\",\"url\":\"https:\/\/rawcyclingmag.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"contentUrl\":\"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png\",\"width\":300,\"height\":140,\"caption\":\"RAW Cycling Magazine\"},\"image\":{\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/facebook.com\/rawcyclingmag\",\"https:\/\/x.com\/rawcyclingmag\",\"http:\/\/instagram.com\/rawcyclingmag\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2\",\"name\":\"Javi Angulo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g\",\"caption\":\"Javi Angulo\"},\"description\":\"Javi es nuestro corresponsal en B\u00e9lgica, y trata de contrarrestar su obsesiva pasi\u00f3n por el an\u00e1lisis de datos con la relajante acci\u00f3n (o eso es lo que dice) de crear contenido para la revista. Javi is based in Belgium and tries to compensate for his obsessive passion for data analytics with the relaxing action (that's what he says) of creating content for the magazine.\",\"sameAs\":[\"https:\/\/www.instagram.com\/javiangulog\/\"],\"url\":\"https:\/\/rawcyclingmag.com\/es\/author\/javi\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lael Wilcox: I just want to ride - RAW Cycling Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/","og_locale":"es_ES","og_type":"article","og_title":"Lael Wilcox: I just want to ride","og_description":"A ra\u00edz del lanzamiento al p\u00fablico de \u201cI Just Want to Ride\u201d, la pel\u00edcula que narra la historia de Lael","og_url":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/","og_site_name":"RAW Cycling Magazine","article_publisher":"http:\/\/facebook.com\/rawcyclingmag","article_published_time":"2019-11-20T20:30:31+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg","type":"image\/jpeg"}],"author":"Javi Angulo","twitter_card":"summary_large_image","twitter_creator":"@rawcyclingmag","twitter_site":"@rawcyclingmag","twitter_misc":{"Escrito por":"Javi Angulo","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#article","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/"},"author":{"name":"Javi Angulo","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2"},"headline":"Lael Wilcox: I just want to ride","datePublished":"2019-11-20T20:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/"},"wordCount":1675,"commentCount":0,"publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg","keywords":["cycling adventures","lael wilcox","women cycling","gravel","silk road mountain race"],"articleSection":["Destacado","Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/","url":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/","name":"Lael Wilcox: I just want to ride - RAW Cycling Magazine","isPartOf":{"@id":"https:\/\/rawcyclingmag.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage"},"thumbnailUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg","datePublished":"2019-11-20T20:30:31+00:00","breadcrumb":{"@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#primaryimage","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2019\/11\/2019_SRMR_Touring_RugileKaladyte_009.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/rawcyclingmag.com\/es\/lael-wilcox-i-just-want-to-ride\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rawcyclingmag.com\/es\/"},{"@type":"ListItem","position":2,"name":"Lael Wilcox: I just want to ride"}]},{"@type":"WebSite","@id":"https:\/\/rawcyclingmag.com\/es\/#website","url":"https:\/\/rawcyclingmag.com\/es\/","name":"RAW Cycling Magazine","description":"","publisher":{"@id":"https:\/\/rawcyclingmag.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rawcyclingmag.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rawcyclingmag.com\/es\/#organization","name":"RAW Cycling Magazine","url":"https:\/\/rawcyclingmag.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","contentUrl":"https:\/\/rawcyclingmag.com\/wp-content\/uploads\/2018\/03\/RawMagazine.orange.medium.png","width":300,"height":140,"caption":"RAW Cycling Magazine"},"image":{"@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/rawcyclingmag","https:\/\/x.com\/rawcyclingmag","http:\/\/instagram.com\/rawcyclingmag"]},{"@type":"Person","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/9a9334e46cc1757dface39a245240ac2","name":"Javi Angulo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rawcyclingmag.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43ed55df3e74b6c072beb9233deb1a217e863d4c5f7f1b3e22ac72c861b226df?s=96&d=mm&r=g","caption":"Javi Angulo"},"description":"Javi es nuestro corresponsal en B\u00e9lgica, y trata de contrarrestar su obsesiva pasi\u00f3n por el an\u00e1lisis de datos con la relajante acci\u00f3n (o eso es lo que dice) de crear contenido para la revista. Javi is based in Belgium and tries to compensate for his obsessive passion for data analytics with the relaxing action (that's what he says) of creating content for the magazine.","sameAs":["https:\/\/www.instagram.com\/javiangulog\/"],"url":"https:\/\/rawcyclingmag.com\/es\/author\/javi\/"}]}},"_links":{"self":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/36631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/comments?post=36631"}],"version-history":[{"count":0,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/posts\/36631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media\/28455"}],"wp:attachment":[{"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/media?parent=36631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/categories?post=36631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rawcyclingmag.com\/es\/wp-json\/wp\/v2\/tags?post=36631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}